{"id":4934,"date":"2020-09-11T06:41:16","date_gmt":"2020-09-11T06:41:16","guid":{"rendered":"https:\/\/www.nordex-online.com\/de\/?p=4934"},"modified":"2023-04-24T11:12:26","modified_gmt":"2023-04-24T11:12:26","slug":"nordex-group-nimmt-planmaessig-im-sinne-der-qualitaetssicherung-getriebe-der-erstanlagen-des-typs-n149-4-0-4-5-unter-die-lupe","status":"publish","type":"post","link":"https:\/\/www.nordex-online.com\/de\/2020\/09\/nordex-group-nimmt-planmaessig-im-sinne-der-qualitaetssicherung-getriebe-der-erstanlagen-des-typs-n149-4-0-4-5-unter-die-lupe\/","title":{"rendered":"Nordex Group nimmt planm\u00e4\u00dfig im Sinne der Qualit\u00e4tssicherung Getriebe der Erstanlagen des Typs N149\/4.0-4.5 unter die Lupe"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Hamburg, 11. September 2020. Im Rahmen des regul\u00e4ren Validierungs- und Zertifizierungsprozesses ihrer Anlagen der Delta4000 Baureihe hat die Nordex Group die erstverbauten Getriebe von zwei Turbinen des Typs N149\/4.0-4.5 im nieders\u00e4chsischen Wennerstorf getauscht. Die im Jahr 2018 an diesem Standort errichteten Turbinen sind die weltweit ersten Delta4000-Anlagen dieses Modells.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Getriebe waren seit August beziehungsweise November 2018 im Einsatz und werden nach den ersten 15 und 24 Betriebsmonaten einer detaillierten Zustandsbewertung unterzogen. Dabei zerlegt der Hersteller die Getriebe fachgerecht in alle Einzelteile, um eine qualifizierte Bewertung mit den Lagerherstellern und den Nordex-Experten vorzunehmen. Das Ziel ist es, die theoretisch ermittelte Zuverl\u00e4ssigkeit abzusichern und fr\u00fchzeitig Erkenntnisse aus dem bisherigen Betrieb der Getriebe in die Serien- und Weiterentwicklungen von Windenergieanlagen mit mehr als 4 MW Nennleistung einflie\u00dfen zu lassen. Au\u00dferdem erh\u00e4lt die Nordex Group relevante Erkenntnisse zur Best\u00e4tigung der Getriebeauslegung sowie zur Optimierung der Wartung. Der Triebstrang ist so konzipiert, dass Getriebe verschiedener Hersteller verbaut werden k\u00f6nnen. Diese geplanten Getriebetausche erm\u00f6glichen es der Nordex Group, Getriebe unterschiedlicher Hersteller einzubauen und deren Verhalten sowie Leistungsf\u00e4higkeit im realen Betrieb zu testen und zu vergleichen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Im Windpark Wennerstorf wurde das erste Getriebe einer Anlage wie geplant bereits im Februar 2020 getauscht, das zweite der Nachbaranlage erfolgte planm\u00e4\u00dfig jetzt im September.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bereits zum zweiten Mal kam zum Austausch der 4MW+ Getriebe ein sogenannter \u201eSelf-Hoisting Crane (SHC)\u201c zum Einsatz, der im Maschinenhaus der Windenergieanlage montiert wird. Dieser Selbsthebekran klettert an einem eigenen Hubseil am Turm der Anlage hoch und installiert sich auf der Oberseite des Maschinenhauses. Dadurch ist er schnell und mobil einsetzbar, ben\u00f6tigt wenig Platz auf dem Erdboden und zeichnet sich durch niedrigere Einsatzkosten aus. Insbesondere f\u00fcr abgelegene Regionen, bei Anlagen mit sehr hohen T\u00fcrmen oder in L\u00e4ndern mit generell hohen Krankosten ist diese L\u00f6sung im Vergleich zu konventionellen Kr\u00e4nen ein deutlicher Vorteil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Nordex Group im Profil<br>Die Gruppe hat \u00fcber 29 GW Windenergieleistung in \u00fcber 40 M\u00e4rkten installiert und erzielte im Jahr 2019 einen Umsatz von etwa EUR 3,3 Mrd. Das Unternehmen besch\u00e4ftigt derzeit \u00fcber 7.900 Mitarbeiter. Zum Fertigungsverbund geh\u00f6ren Werke in Deutschland, Spanien, Brasilien, den USA, Indien, Argentinien und Mexiko. Das Produktprogramm konzentriert sich auf Onshore-Turbinen der 2,4- bis 5,X-MW-Klasse, die auf die Marktanforderungen von L\u00e4ndern mit begrenzten Ausbaufl\u00e4chen und Regionen mit begrenzten Netzkapazit\u00e4ten ausgelegt sind.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hamburg, 11. September 2020. Im Rahmen des regul\u00e4ren Validierungs- und Zertifizierungsprozesses ihrer Anlagen der Delta4000 Baureihe hat die Nordex Group die erstverbauten Getriebe von zwei Turbinen des Typs N149\/4.0-4.5 im nieders\u00e4chsischen Wennerstorf getauscht. Die im Jahr 2018 an diesem Standort errichteten Turbinen sind die weltweit ersten Delta4000-Anlagen dieses Modells. Die Getriebe waren seit August beziehungsweise [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":4936,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_trash_the_other_posts":false,"editor_notices":[],"footnotes":""},"categories":[1249],"tags":[],"class_list":["post-4934","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-company-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Nordex Group nimmt planm\u00e4\u00dfig im Sinne der Qualit\u00e4tssicherung Getriebe der Erstanlagen des Typs N149\/4.0-4.5 unter die Lupe - Nordex SE - Deutsch<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.nordex-online.com\/de\/2020\/09\/nordex-group-nimmt-planmaessig-im-sinne-der-qualitaetssicherung-getriebe-der-erstanlagen-des-typs-n149-4-0-4-5-unter-die-lupe\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nordex Group nimmt planm\u00e4\u00dfig im Sinne der Qualit\u00e4tssicherung Getriebe der Erstanlagen des Typs N149\/4.0-4.5 unter die Lupe\" \/>\n<meta property=\"og:description\" content=\"Hamburg, 11. September 2020. Im Rahmen des regul\u00e4ren Validierungs- und Zertifizierungsprozesses ihrer Anlagen der Delta4000 Baureihe hat die Nordex Group die erstverbauten Getriebe von zwei Turbinen des Typs N149\/4.0-4.5 im nieders\u00e4chsischen Wennerstorf getauscht. Die im Jahr 2018 an diesem Standort errichteten Turbinen sind die weltweit ersten Delta4000-Anlagen dieses Modells. Die Getriebe waren seit August beziehungsweise [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nordex-online.com\/de\/2020\/09\/nordex-group-nimmt-planmaessig-im-sinne-der-qualitaetssicherung-getriebe-der-erstanlagen-des-typs-n149-4-0-4-5-unter-die-lupe\/\" \/>\n<meta property=\"og:site_name\" content=\"Nordex SE - Deutsch\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-11T06:41:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-24T11:12:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.nordex-online.com\/wp-content\/uploads\/sites\/3\/2020\/09\/SHC_Wennerstorf-3-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Losada, Felix\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Losada, Felix\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2020\\\/09\\\/nordex-group-nimmt-planmaessig-im-sinne-der-qualitaetssicherung-getriebe-der-erstanlagen-des-typs-n149-4-0-4-5-unter-die-lupe\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2020\\\/09\\\/nordex-group-nimmt-planmaessig-im-sinne-der-qualitaetssicherung-getriebe-der-erstanlagen-des-typs-n149-4-0-4-5-unter-die-lupe\\\/\"},\"author\":{\"name\":\"Losada, Felix\",\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/#\\\/schema\\\/person\\\/55c351e379afa364550f317a2ed49f88\"},\"headline\":\"Nordex Group nimmt planm\u00e4\u00dfig im Sinne der Qualit\u00e4tssicherung Getriebe der Erstanlagen des Typs N149\\\/4.0-4.5 unter die Lupe\",\"datePublished\":\"2020-09-11T06:41:16+00:00\",\"dateModified\":\"2023-04-24T11:12:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2020\\\/09\\\/nordex-group-nimmt-planmaessig-im-sinne-der-qualitaetssicherung-getriebe-der-erstanlagen-des-typs-n149-4-0-4-5-unter-die-lupe\\\/\"},\"wordCount\":405,\"publisher\":{\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2020\\\/09\\\/nordex-group-nimmt-planmaessig-im-sinne-der-qualitaetssicherung-getriebe-der-erstanlagen-des-typs-n149-4-0-4-5-unter-die-lupe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.nordex-online.com\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/09\\\/SHC_Wennerstorf-3-scaled.jpg\",\"articleSection\":[\"Unternehmensneuigkeiten\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2020\\\/09\\\/nordex-group-nimmt-planmaessig-im-sinne-der-qualitaetssicherung-getriebe-der-erstanlagen-des-typs-n149-4-0-4-5-unter-die-lupe\\\/\",\"url\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2020\\\/09\\\/nordex-group-nimmt-planmaessig-im-sinne-der-qualitaetssicherung-getriebe-der-erstanlagen-des-typs-n149-4-0-4-5-unter-die-lupe\\\/\",\"name\":\"Nordex Group nimmt planm\u00e4\u00dfig im Sinne der Qualit\u00e4tssicherung Getriebe der Erstanlagen des Typs N149\\\/4.0-4.5 unter die Lupe - Nordex SE - Deutsch\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2020\\\/09\\\/nordex-group-nimmt-planmaessig-im-sinne-der-qualitaetssicherung-getriebe-der-erstanlagen-des-typs-n149-4-0-4-5-unter-die-lupe\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2020\\\/09\\\/nordex-group-nimmt-planmaessig-im-sinne-der-qualitaetssicherung-getriebe-der-erstanlagen-des-typs-n149-4-0-4-5-unter-die-lupe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.nordex-online.com\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/09\\\/SHC_Wennerstorf-3-scaled.jpg\",\"datePublished\":\"2020-09-11T06:41:16+00:00\",\"dateModified\":\"2023-04-24T11:12:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2020\\\/09\\\/nordex-group-nimmt-planmaessig-im-sinne-der-qualitaetssicherung-getriebe-der-erstanlagen-des-typs-n149-4-0-4-5-unter-die-lupe\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2020\\\/09\\\/nordex-group-nimmt-planmaessig-im-sinne-der-qualitaetssicherung-getriebe-der-erstanlagen-des-typs-n149-4-0-4-5-unter-die-lupe\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2020\\\/09\\\/nordex-group-nimmt-planmaessig-im-sinne-der-qualitaetssicherung-getriebe-der-erstanlagen-des-typs-n149-4-0-4-5-unter-die-lupe\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.nordex-online.com\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/09\\\/SHC_Wennerstorf-3-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.nordex-online.com\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/09\\\/SHC_Wennerstorf-3-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2020\\\/09\\\/nordex-group-nimmt-planmaessig-im-sinne-der-qualitaetssicherung-getriebe-der-erstanlagen-des-typs-n149-4-0-4-5-unter-die-lupe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nordex Group nimmt planm\u00e4\u00dfig im Sinne der Qualit\u00e4tssicherung Getriebe der Erstanlagen des Typs N149\\\/4.0-4.5 unter die Lupe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/\",\"name\":\"Nordex SE - Deutsch\",\"description\":\"Manufacture, installation and maintenance of wind turbines.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/#organization\",\"name\":\"Nordex SE - Deutsch\",\"url\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.nordex-online.com\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/07\\\/cropped-cropped-cropped-Combined-Logos_cmyk_PNG.png\",\"contentUrl\":\"https:\\\/\\\/www.nordex-online.com\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/07\\\/cropped-cropped-cropped-Combined-Logos_cmyk_PNG.png\",\"width\":1181,\"height\":353,\"caption\":\"Nordex SE - Deutsch\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/#\\\/schema\\\/person\\\/55c351e379afa364550f317a2ed49f88\",\"name\":\"Losada, Felix\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a5ebb61026b7e94f6c40e5f0489357cd086d32a53cd9595871c61860cce67a8e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a5ebb61026b7e94f6c40e5f0489357cd086d32a53cd9595871c61860cce67a8e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a5ebb61026b7e94f6c40e5f0489357cd086d32a53cd9595871c61860cce67a8e?s=96&d=mm&r=g\",\"caption\":\"Losada, Felix\"},\"url\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/author\\\/flosada\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Nordex Group nimmt planm\u00e4\u00dfig im Sinne der Qualit\u00e4tssicherung Getriebe der Erstanlagen des Typs N149\/4.0-4.5 unter die Lupe - Nordex SE - Deutsch","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.nordex-online.com\/de\/2020\/09\/nordex-group-nimmt-planmaessig-im-sinne-der-qualitaetssicherung-getriebe-der-erstanlagen-des-typs-n149-4-0-4-5-unter-die-lupe\/","og_locale":"de_DE","og_type":"article","og_title":"Nordex Group nimmt planm\u00e4\u00dfig im Sinne der Qualit\u00e4tssicherung Getriebe der Erstanlagen des Typs N149\/4.0-4.5 unter die Lupe","og_description":"Hamburg, 11. September 2020. Im Rahmen des regul\u00e4ren Validierungs- und Zertifizierungsprozesses ihrer Anlagen der Delta4000 Baureihe hat die Nordex Group die erstverbauten Getriebe von zwei Turbinen des Typs N149\/4.0-4.5 im nieders\u00e4chsischen Wennerstorf getauscht. Die im Jahr 2018 an diesem Standort errichteten Turbinen sind die weltweit ersten Delta4000-Anlagen dieses Modells. Die Getriebe waren seit August beziehungsweise [&hellip;]","og_url":"https:\/\/www.nordex-online.com\/de\/2020\/09\/nordex-group-nimmt-planmaessig-im-sinne-der-qualitaetssicherung-getriebe-der-erstanlagen-des-typs-n149-4-0-4-5-unter-die-lupe\/","og_site_name":"Nordex SE - Deutsch","article_published_time":"2020-09-11T06:41:16+00:00","article_modified_time":"2023-04-24T11:12:26+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.nordex-online.com\/wp-content\/uploads\/sites\/3\/2020\/09\/SHC_Wennerstorf-3-scaled.jpg","type":"image\/jpeg"}],"author":"Losada, Felix","twitter_card":"summary_large_image","twitter_misc":{"Geschrieben von":"Losada, Felix","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.nordex-online.com\/de\/2020\/09\/nordex-group-nimmt-planmaessig-im-sinne-der-qualitaetssicherung-getriebe-der-erstanlagen-des-typs-n149-4-0-4-5-unter-die-lupe\/#article","isPartOf":{"@id":"https:\/\/www.nordex-online.com\/de\/2020\/09\/nordex-group-nimmt-planmaessig-im-sinne-der-qualitaetssicherung-getriebe-der-erstanlagen-des-typs-n149-4-0-4-5-unter-die-lupe\/"},"author":{"name":"Losada, Felix","@id":"https:\/\/www.nordex-online.com\/de\/#\/schema\/person\/55c351e379afa364550f317a2ed49f88"},"headline":"Nordex Group nimmt planm\u00e4\u00dfig im Sinne der Qualit\u00e4tssicherung Getriebe der Erstanlagen des Typs N149\/4.0-4.5 unter die Lupe","datePublished":"2020-09-11T06:41:16+00:00","dateModified":"2023-04-24T11:12:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.nordex-online.com\/de\/2020\/09\/nordex-group-nimmt-planmaessig-im-sinne-der-qualitaetssicherung-getriebe-der-erstanlagen-des-typs-n149-4-0-4-5-unter-die-lupe\/"},"wordCount":405,"publisher":{"@id":"https:\/\/www.nordex-online.com\/de\/#organization"},"image":{"@id":"https:\/\/www.nordex-online.com\/de\/2020\/09\/nordex-group-nimmt-planmaessig-im-sinne-der-qualitaetssicherung-getriebe-der-erstanlagen-des-typs-n149-4-0-4-5-unter-die-lupe\/#primaryimage"},"thumbnailUrl":"https:\/\/www.nordex-online.com\/wp-content\/uploads\/sites\/3\/2020\/09\/SHC_Wennerstorf-3-scaled.jpg","articleSection":["Unternehmensneuigkeiten"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.nordex-online.com\/de\/2020\/09\/nordex-group-nimmt-planmaessig-im-sinne-der-qualitaetssicherung-getriebe-der-erstanlagen-des-typs-n149-4-0-4-5-unter-die-lupe\/","url":"https:\/\/www.nordex-online.com\/de\/2020\/09\/nordex-group-nimmt-planmaessig-im-sinne-der-qualitaetssicherung-getriebe-der-erstanlagen-des-typs-n149-4-0-4-5-unter-die-lupe\/","name":"Nordex Group nimmt planm\u00e4\u00dfig im Sinne der Qualit\u00e4tssicherung Getriebe der Erstanlagen des Typs N149\/4.0-4.5 unter die Lupe - Nordex SE - Deutsch","isPartOf":{"@id":"https:\/\/www.nordex-online.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.nordex-online.com\/de\/2020\/09\/nordex-group-nimmt-planmaessig-im-sinne-der-qualitaetssicherung-getriebe-der-erstanlagen-des-typs-n149-4-0-4-5-unter-die-lupe\/#primaryimage"},"image":{"@id":"https:\/\/www.nordex-online.com\/de\/2020\/09\/nordex-group-nimmt-planmaessig-im-sinne-der-qualitaetssicherung-getriebe-der-erstanlagen-des-typs-n149-4-0-4-5-unter-die-lupe\/#primaryimage"},"thumbnailUrl":"https:\/\/www.nordex-online.com\/wp-content\/uploads\/sites\/3\/2020\/09\/SHC_Wennerstorf-3-scaled.jpg","datePublished":"2020-09-11T06:41:16+00:00","dateModified":"2023-04-24T11:12:26+00:00","breadcrumb":{"@id":"https:\/\/www.nordex-online.com\/de\/2020\/09\/nordex-group-nimmt-planmaessig-im-sinne-der-qualitaetssicherung-getriebe-der-erstanlagen-des-typs-n149-4-0-4-5-unter-die-lupe\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.nordex-online.com\/de\/2020\/09\/nordex-group-nimmt-planmaessig-im-sinne-der-qualitaetssicherung-getriebe-der-erstanlagen-des-typs-n149-4-0-4-5-unter-die-lupe\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.nordex-online.com\/de\/2020\/09\/nordex-group-nimmt-planmaessig-im-sinne-der-qualitaetssicherung-getriebe-der-erstanlagen-des-typs-n149-4-0-4-5-unter-die-lupe\/#primaryimage","url":"https:\/\/www.nordex-online.com\/wp-content\/uploads\/sites\/3\/2020\/09\/SHC_Wennerstorf-3-scaled.jpg","contentUrl":"https:\/\/www.nordex-online.com\/wp-content\/uploads\/sites\/3\/2020\/09\/SHC_Wennerstorf-3-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/www.nordex-online.com\/de\/2020\/09\/nordex-group-nimmt-planmaessig-im-sinne-der-qualitaetssicherung-getriebe-der-erstanlagen-des-typs-n149-4-0-4-5-unter-die-lupe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.nordex-online.com\/de\/"},{"@type":"ListItem","position":2,"name":"Nordex Group nimmt planm\u00e4\u00dfig im Sinne der Qualit\u00e4tssicherung Getriebe der Erstanlagen des Typs N149\/4.0-4.5 unter die Lupe"}]},{"@type":"WebSite","@id":"https:\/\/www.nordex-online.com\/de\/#website","url":"https:\/\/www.nordex-online.com\/de\/","name":"Nordex SE - Deutsch","description":"Manufacture, installation and maintenance of wind turbines.","publisher":{"@id":"https:\/\/www.nordex-online.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nordex-online.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.nordex-online.com\/de\/#organization","name":"Nordex SE - Deutsch","url":"https:\/\/www.nordex-online.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.nordex-online.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.nordex-online.com\/wp-content\/uploads\/sites\/3\/2024\/07\/cropped-cropped-cropped-Combined-Logos_cmyk_PNG.png","contentUrl":"https:\/\/www.nordex-online.com\/wp-content\/uploads\/sites\/3\/2024\/07\/cropped-cropped-cropped-Combined-Logos_cmyk_PNG.png","width":1181,"height":353,"caption":"Nordex SE - Deutsch"},"image":{"@id":"https:\/\/www.nordex-online.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.nordex-online.com\/de\/#\/schema\/person\/55c351e379afa364550f317a2ed49f88","name":"Losada, Felix","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a5ebb61026b7e94f6c40e5f0489357cd086d32a53cd9595871c61860cce67a8e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a5ebb61026b7e94f6c40e5f0489357cd086d32a53cd9595871c61860cce67a8e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a5ebb61026b7e94f6c40e5f0489357cd086d32a53cd9595871c61860cce67a8e?s=96&d=mm&r=g","caption":"Losada, Felix"},"url":"https:\/\/www.nordex-online.com\/de\/author\/flosada\/"}]}},"_links":{"self":[{"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/posts\/4934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/comments?post=4934"}],"version-history":[{"count":1,"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/posts\/4934\/revisions"}],"predecessor-version":[{"id":4935,"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/posts\/4934\/revisions\/4935"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/media\/4936"}],"wp:attachment":[{"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/media?parent=4934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/categories?post=4934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/tags?post=4934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}