{"id":4929,"date":"2020-09-04T11:28:13","date_gmt":"2020-09-04T11:28:13","guid":{"rendered":"https:\/\/www.nordex-online.com\/de\/?p=4929"},"modified":"2023-04-24T11:12:27","modified_gmt":"2023-04-24T11:12:27","slug":"teil-1-von-grossprojekt-wieringermeer-ist-am-netz","status":"publish","type":"post","link":"https:\/\/www.nordex-online.com\/de\/2020\/09\/teil-1-von-grossprojekt-wieringermeer-ist-am-netz\/","title":{"rendered":"Teil 1 von Gro\u00dfprojekt Wieringermeer ist am Netz"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Die Nordex Group hat den ersten Teil des niederl\u00e4ndischen 300-MW-Projekts Wieringermeer f\u00fcr ihren Kunden Vattenfall erfolgreich abgeschlossen: Die letzte der 50 N117\/3600-Turbinen ging im August ans Netz. Der Standort des Projekts \u2013 ganz zu schweigen von den Auswirkungen der COVID-19-Pandemie \u2013 stellte besondere Herausforderungen dar. Der Bau der n\u00e4chsten Bauphase mit weiteren 32 117\/3600-Turbinen ist im vollen Gang.<br><br><strong>Technische, topografische und \u00f6kologische Herausforderungen gemeistert<\/strong><br><br>Am Standort 60 Kilometer n\u00f6rdlich von Amsterdam herrschen hervorragende Windbedingungen, allerdings ist Wieringermeer ein Polder, ein eingedeichtes Gebiet mit zur\u00fcckgewonnenem Land, das sieben Meter unter dem Meeresspiegel liegt. Die 300 km<sup>2<\/sup> gro\u00dfe Fl\u00e4che ist von Kan\u00e4len durchzogen und umfasst auch einen gesch\u00fctzten Wald \u2013 eine besondere Herausforderung f\u00fcr Logistik und Errichtung. Da nicht viel geeignete Lagerfl\u00e4che vorhanden war, hat die Nordex Group T\u00fcrme, Maschinenh\u00e4user, Triebstr\u00e4nge und Naben just in time geliefert. Bei sieben unterschiedlich konfigurierten Turbinen, beispielsweise mit Metallpartikelz\u00e4hler oder Flugbefeuerung, kam es dabei zus\u00e4tzlich darauf an, die richtige Technik an die genau daf\u00fcr vorgesehene Stelle zu liefern.<br><br>Aufgrund der geringen Tragf\u00e4higkeit des Bodens mussten die Fundamente mit einer Pfahlgr\u00fcndung versehen und zudem um 1,5 Meter erh\u00f6ht werden, um \u00dcberflutungen vorzubeugen. Zudem limitierten Tierschutzma\u00dfnahmen den Zugang zu einigen Turbinen sowie die Anzahl erlaubten der Kr\u00e4ne auf der Baustelle.<br><br><strong>Ma\u00dfgeschneiderte Prozesse verhelfen zum Erfolg<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Nordex Group hat ihre Prozesse den spezifischen Erfordernissen dieses Projekts angepasst. So hat ein Token basiertes Genehmigungssystem sichergestellt, dass mehrere Auftragnehmer zuverl\u00e4ssig einer bestimmten Turbine zugewiesen werden k\u00f6nnen. Dieses Vorgehen vermied Konflikte und verbesserte die Effizienz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zudem wurden neue Funktionen wie z.B. ein &#8222;Technical Project Manager&#8220; (TPM) als Schnittstelle in Engineering und andere technische Abteilungen eingesetzt. Dar\u00fcber hinaus gab es Qualit\u00e4ts- und Dokumentationsmanager sowie ein starkes HSE-Team vor Ort, um den hohen Anforderungen von Vattenfall gerecht zu werden. CEO Jos\u00e9 Luis Blanco: \u201eFlexibilit\u00e4t geh\u00f6rt zu unserem Selbstverst\u00e4ndnis. Diese Anpassung zeigt, dass wir die Anforderungen und Herausforderungen unserer Kunden verstehen, und einige der neuen Prozesse werden auch bereits bei anderen Gro\u00dfprojekten erfolgreich eingesetzt.\u201c<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Projektunterbrechung durch COVID-19 vorgebeugt<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auf dem H\u00f6hepunkt der Arbeiten waren 8 gro\u00dfe Kr\u00e4ne und \u00fcber 100 Mitarbeiter auf der Baustelle besch\u00e4ftigt. Damit diese gro\u00dfe Anzahl an Personen auch w\u00e4hrend der COVID-19-Pandemie sicher auf der Baustelle arbeiten konnte, hat die Nordex Group \u00fcber ihre allgemeinen Vorkehrungen bez\u00fcglich Reisen und Hygiene hinaus eigens einen niederl\u00e4ndischen Sanit\u00e4ter eingestellt. Seine Aufgabe war es, jeden Tag vor Arbeitsbeginn die Temperatur aller Besch\u00e4ftigten vor Ort zu kontrollieren und medizinische Beratung zu leisten, falls jemand Symptome zeigen sollte. Diese Ma\u00dfnahme gab den Besch\u00e4ftigten eine gewisse Sicherheit, sich durch die Arbeit und dem damit verbundenen Kontakt mit vielen Personen nicht einem erh\u00f6hten Infektionsrisiko auszusetzen \u2013 mit Erfolg: Zu keinem Zeitpunkt musste die Arbeit am Projekt aufgrund der Pandemie unterbrochen werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Errichtung der Erweiterungsstufe mit 32 N117\/3600 ist im vollen Gang. Nach ihrem Abschluss wird der Windpark j\u00e4hrlich insgesamt rund 1,3 Terawattstunden (= 1,3 Milliarden Kilowattstunden) gr\u00fcnen Windstrom erzeugen. Wieringermeer wird eines der ersten Projekte sein, bei dem das neue Betriebssystem Nordex OS zum Einsatz kommt. Das System kann beliebige Komponenten (z.B. zus\u00e4tzliche Rotorblattsensoren) einbinden und bietet dadurch optimierte M\u00f6glichkeiten der Windpark\u00fcberwachung. Seine neue Architektur erh\u00f6ht die Verf\u00fcgbarkeit des SCADA-Systems und ist mit k\u00fcnftigen Hardwaregenerationen kompatibel.<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Foto: Vattenfall\/Robert Assies<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Nordex Group hat den ersten Teil des niederl\u00e4ndischen 300-MW-Projekts Wieringermeer f\u00fcr ihren Kunden Vattenfall erfolgreich abgeschlossen: Die letzte der 50 N117\/3600-Turbinen ging im August ans Netz. Der Standort des Projekts \u2013 ganz zu schweigen von den Auswirkungen der COVID-19-Pandemie \u2013 stellte besondere Herausforderungen dar. Der Bau der n\u00e4chsten Bauphase mit weiteren 32 117\/3600-Turbinen ist [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":4930,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_trash_the_other_posts":false,"editor_notices":[],"footnotes":""},"categories":[1249],"tags":[],"class_list":["post-4929","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-company-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Teil 1 von Gro\u00dfprojekt Wieringermeer ist am Netz - Nordex SE - Deutsch<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.nordex-online.com\/de\/2020\/09\/teil-1-von-grossprojekt-wieringermeer-ist-am-netz\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Teil 1 von Gro\u00dfprojekt Wieringermeer ist am Netz\" \/>\n<meta property=\"og:description\" content=\"Die Nordex Group hat den ersten Teil des niederl\u00e4ndischen 300-MW-Projekts Wieringermeer f\u00fcr ihren Kunden Vattenfall erfolgreich abgeschlossen: Die letzte der 50 N117\/3600-Turbinen ging im August ans Netz. Der Standort des Projekts \u2013 ganz zu schweigen von den Auswirkungen der COVID-19-Pandemie \u2013 stellte besondere Herausforderungen dar. Der Bau der n\u00e4chsten Bauphase mit weiteren 32 117\/3600-Turbinen ist [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nordex-online.com\/de\/2020\/09\/teil-1-von-grossprojekt-wieringermeer-ist-am-netz\/\" \/>\n<meta property=\"og:site_name\" content=\"Nordex SE - Deutsch\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-04T11:28:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-24T11:12:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.nordex-online.com\/wp-content\/uploads\/sites\/3\/2020\/09\/WRM_2029_012-200715_12h45.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2200\" \/>\n\t<meta property=\"og:image:height\" content=\"1466\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sjaekel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"sjaekel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2020\\\/09\\\/teil-1-von-grossprojekt-wieringermeer-ist-am-netz\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2020\\\/09\\\/teil-1-von-grossprojekt-wieringermeer-ist-am-netz\\\/\"},\"author\":{\"name\":\"sjaekel\",\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/#\\\/schema\\\/person\\\/ea5575071aa13ab4c5c1d7ec5845e3c0\"},\"headline\":\"Teil 1 von Gro\u00dfprojekt Wieringermeer ist am Netz\",\"datePublished\":\"2020-09-04T11:28:13+00:00\",\"dateModified\":\"2023-04-24T11:12:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2020\\\/09\\\/teil-1-von-grossprojekt-wieringermeer-ist-am-netz\\\/\"},\"wordCount\":572,\"publisher\":{\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2020\\\/09\\\/teil-1-von-grossprojekt-wieringermeer-ist-am-netz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.nordex-online.com\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/09\\\/WRM_2029_012-200715_12h45.jpg\",\"articleSection\":[\"Unternehmensneuigkeiten\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2020\\\/09\\\/teil-1-von-grossprojekt-wieringermeer-ist-am-netz\\\/\",\"url\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2020\\\/09\\\/teil-1-von-grossprojekt-wieringermeer-ist-am-netz\\\/\",\"name\":\"Teil 1 von Gro\u00dfprojekt Wieringermeer ist am Netz - Nordex SE - Deutsch\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2020\\\/09\\\/teil-1-von-grossprojekt-wieringermeer-ist-am-netz\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2020\\\/09\\\/teil-1-von-grossprojekt-wieringermeer-ist-am-netz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.nordex-online.com\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/09\\\/WRM_2029_012-200715_12h45.jpg\",\"datePublished\":\"2020-09-04T11:28:13+00:00\",\"dateModified\":\"2023-04-24T11:12:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2020\\\/09\\\/teil-1-von-grossprojekt-wieringermeer-ist-am-netz\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2020\\\/09\\\/teil-1-von-grossprojekt-wieringermeer-ist-am-netz\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2020\\\/09\\\/teil-1-von-grossprojekt-wieringermeer-ist-am-netz\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.nordex-online.com\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/09\\\/WRM_2029_012-200715_12h45.jpg\",\"contentUrl\":\"https:\\\/\\\/www.nordex-online.com\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/09\\\/WRM_2029_012-200715_12h45.jpg\",\"width\":2200,\"height\":1466,\"caption\":\"Use photo credit \\\"photo: Vattenfall\\\/Robert Assies\\\" when used for publication\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2020\\\/09\\\/teil-1-von-grossprojekt-wieringermeer-ist-am-netz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Teil 1 von Gro\u00dfprojekt Wieringermeer ist am Netz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/\",\"name\":\"Nordex SE - Deutsch\",\"description\":\"Manufacture, installation and maintenance of wind turbines.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/#organization\",\"name\":\"Nordex SE - Deutsch\",\"url\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.nordex-online.com\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/07\\\/cropped-cropped-cropped-Combined-Logos_cmyk_PNG.png\",\"contentUrl\":\"https:\\\/\\\/www.nordex-online.com\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/07\\\/cropped-cropped-cropped-Combined-Logos_cmyk_PNG.png\",\"width\":1181,\"height\":353,\"caption\":\"Nordex SE - Deutsch\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/#\\\/schema\\\/person\\\/ea5575071aa13ab4c5c1d7ec5845e3c0\",\"name\":\"sjaekel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8becc19786279727be494a4179ad1169b76a822760745dc96cec18936179a5cd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8becc19786279727be494a4179ad1169b76a822760745dc96cec18936179a5cd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8becc19786279727be494a4179ad1169b76a822760745dc96cec18936179a5cd?s=96&d=mm&r=g\",\"caption\":\"sjaekel\"},\"url\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/author\\\/sjaekel\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Teil 1 von Gro\u00dfprojekt Wieringermeer ist am Netz - Nordex SE - Deutsch","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.nordex-online.com\/de\/2020\/09\/teil-1-von-grossprojekt-wieringermeer-ist-am-netz\/","og_locale":"de_DE","og_type":"article","og_title":"Teil 1 von Gro\u00dfprojekt Wieringermeer ist am Netz","og_description":"Die Nordex Group hat den ersten Teil des niederl\u00e4ndischen 300-MW-Projekts Wieringermeer f\u00fcr ihren Kunden Vattenfall erfolgreich abgeschlossen: Die letzte der 50 N117\/3600-Turbinen ging im August ans Netz. Der Standort des Projekts \u2013 ganz zu schweigen von den Auswirkungen der COVID-19-Pandemie \u2013 stellte besondere Herausforderungen dar. Der Bau der n\u00e4chsten Bauphase mit weiteren 32 117\/3600-Turbinen ist [&hellip;]","og_url":"https:\/\/www.nordex-online.com\/de\/2020\/09\/teil-1-von-grossprojekt-wieringermeer-ist-am-netz\/","og_site_name":"Nordex SE - Deutsch","article_published_time":"2020-09-04T11:28:13+00:00","article_modified_time":"2023-04-24T11:12:27+00:00","og_image":[{"width":2200,"height":1466,"url":"https:\/\/www.nordex-online.com\/wp-content\/uploads\/sites\/3\/2020\/09\/WRM_2029_012-200715_12h45.jpg","type":"image\/jpeg"}],"author":"sjaekel","twitter_card":"summary_large_image","twitter_misc":{"Geschrieben von":"sjaekel","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.nordex-online.com\/de\/2020\/09\/teil-1-von-grossprojekt-wieringermeer-ist-am-netz\/#article","isPartOf":{"@id":"https:\/\/www.nordex-online.com\/de\/2020\/09\/teil-1-von-grossprojekt-wieringermeer-ist-am-netz\/"},"author":{"name":"sjaekel","@id":"https:\/\/www.nordex-online.com\/de\/#\/schema\/person\/ea5575071aa13ab4c5c1d7ec5845e3c0"},"headline":"Teil 1 von Gro\u00dfprojekt Wieringermeer ist am Netz","datePublished":"2020-09-04T11:28:13+00:00","dateModified":"2023-04-24T11:12:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.nordex-online.com\/de\/2020\/09\/teil-1-von-grossprojekt-wieringermeer-ist-am-netz\/"},"wordCount":572,"publisher":{"@id":"https:\/\/www.nordex-online.com\/de\/#organization"},"image":{"@id":"https:\/\/www.nordex-online.com\/de\/2020\/09\/teil-1-von-grossprojekt-wieringermeer-ist-am-netz\/#primaryimage"},"thumbnailUrl":"https:\/\/www.nordex-online.com\/wp-content\/uploads\/sites\/3\/2020\/09\/WRM_2029_012-200715_12h45.jpg","articleSection":["Unternehmensneuigkeiten"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.nordex-online.com\/de\/2020\/09\/teil-1-von-grossprojekt-wieringermeer-ist-am-netz\/","url":"https:\/\/www.nordex-online.com\/de\/2020\/09\/teil-1-von-grossprojekt-wieringermeer-ist-am-netz\/","name":"Teil 1 von Gro\u00dfprojekt Wieringermeer ist am Netz - Nordex SE - Deutsch","isPartOf":{"@id":"https:\/\/www.nordex-online.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.nordex-online.com\/de\/2020\/09\/teil-1-von-grossprojekt-wieringermeer-ist-am-netz\/#primaryimage"},"image":{"@id":"https:\/\/www.nordex-online.com\/de\/2020\/09\/teil-1-von-grossprojekt-wieringermeer-ist-am-netz\/#primaryimage"},"thumbnailUrl":"https:\/\/www.nordex-online.com\/wp-content\/uploads\/sites\/3\/2020\/09\/WRM_2029_012-200715_12h45.jpg","datePublished":"2020-09-04T11:28:13+00:00","dateModified":"2023-04-24T11:12:27+00:00","breadcrumb":{"@id":"https:\/\/www.nordex-online.com\/de\/2020\/09\/teil-1-von-grossprojekt-wieringermeer-ist-am-netz\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.nordex-online.com\/de\/2020\/09\/teil-1-von-grossprojekt-wieringermeer-ist-am-netz\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.nordex-online.com\/de\/2020\/09\/teil-1-von-grossprojekt-wieringermeer-ist-am-netz\/#primaryimage","url":"https:\/\/www.nordex-online.com\/wp-content\/uploads\/sites\/3\/2020\/09\/WRM_2029_012-200715_12h45.jpg","contentUrl":"https:\/\/www.nordex-online.com\/wp-content\/uploads\/sites\/3\/2020\/09\/WRM_2029_012-200715_12h45.jpg","width":2200,"height":1466,"caption":"Use photo credit \"photo: Vattenfall\/Robert Assies\" when used for publication"},{"@type":"BreadcrumbList","@id":"https:\/\/www.nordex-online.com\/de\/2020\/09\/teil-1-von-grossprojekt-wieringermeer-ist-am-netz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.nordex-online.com\/de\/"},{"@type":"ListItem","position":2,"name":"Teil 1 von Gro\u00dfprojekt Wieringermeer ist am Netz"}]},{"@type":"WebSite","@id":"https:\/\/www.nordex-online.com\/de\/#website","url":"https:\/\/www.nordex-online.com\/de\/","name":"Nordex SE - Deutsch","description":"Manufacture, installation and maintenance of wind turbines.","publisher":{"@id":"https:\/\/www.nordex-online.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nordex-online.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.nordex-online.com\/de\/#organization","name":"Nordex SE - Deutsch","url":"https:\/\/www.nordex-online.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.nordex-online.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.nordex-online.com\/wp-content\/uploads\/sites\/3\/2024\/07\/cropped-cropped-cropped-Combined-Logos_cmyk_PNG.png","contentUrl":"https:\/\/www.nordex-online.com\/wp-content\/uploads\/sites\/3\/2024\/07\/cropped-cropped-cropped-Combined-Logos_cmyk_PNG.png","width":1181,"height":353,"caption":"Nordex SE - Deutsch"},"image":{"@id":"https:\/\/www.nordex-online.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.nordex-online.com\/de\/#\/schema\/person\/ea5575071aa13ab4c5c1d7ec5845e3c0","name":"sjaekel","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/8becc19786279727be494a4179ad1169b76a822760745dc96cec18936179a5cd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8becc19786279727be494a4179ad1169b76a822760745dc96cec18936179a5cd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8becc19786279727be494a4179ad1169b76a822760745dc96cec18936179a5cd?s=96&d=mm&r=g","caption":"sjaekel"},"url":"https:\/\/www.nordex-online.com\/de\/author\/sjaekel\/"}]}},"_links":{"self":[{"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/posts\/4929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/comments?post=4929"}],"version-history":[{"count":2,"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/posts\/4929\/revisions"}],"predecessor-version":[{"id":4932,"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/posts\/4929\/revisions\/4932"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/media\/4930"}],"wp:attachment":[{"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/media?parent=4929"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/categories?post=4929"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/tags?post=4929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}