{"id":4892,"date":"2020-08-20T06:01:04","date_gmt":"2020-08-20T06:01:04","guid":{"rendered":"https:\/\/www.nordex-online.com\/de\/?p=4892"},"modified":"2023-04-24T11:12:28","modified_gmt":"2023-04-24T11:12:28","slug":"the-nordex-group-around-the-world-polen","status":"publish","type":"post","link":"https:\/\/www.nordex-online.com\/de\/2020\/08\/the-nordex-group-around-the-world-polen\/","title":{"rendered":"The Nordex Group around the world &#8211; Polen!"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Nachdem die Erneuerbaren Energien in Polen lange Zeit wenig Aufmerksamkeit in der Klima-Politik im Land hatten, setzt Polens Klimaministerium neue Akzente hin zu gr\u00fcnen Investitionen in der polnischen Energiewirtschaft. Polen, das seinen Energiebedarf \u00fcberwiegend mit fossilen Energietr\u00e4gern deckt, k\u00f6nnte damit vor einem Wendepunkt stehen und einen wichtigen Beitrag zur Energiewende leisten. Eine Schl\u00fcsselaufgabe wird dabei sein, alte Kohlekraftwerke durch Erneuerbare Energiequellen zu ersetzen und sich an die Ziele der EU-Klimapolitik weiter anzun\u00e4hern.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In Polen werden Energien seit 2016 durch ein Auktionssystem staatlich gef\u00f6rdert. Energiequellen werden dabei auf unterschiedliche K\u00f6rbe aufgeteilt, die unabh\u00e4ngig voneinander versteigert werden. Onshore-Windenergie ist dabei mit Photovoltaikanlagen (PV) in einem Auktionskorb. Aufgrund der Kosten-Wettbewerbsf\u00e4higkeit von Windenergieanlagen an Land im Vergleich zu anderen Energiequellen wurden zwischen 2018 und 2019 rund 3,3 GW Kapazit\u00e4t an Onshore-Anlagen vergeben. Bis Ende 2020 wird eine weitere Auktionsrunde mit rund 800 MW Onshore-Windenergievolumen und um die 700 MW f\u00fcr PV-Anlagen erwartet. Durch die starke, wettbewerbsf\u00e4hige Position der Onshore-Windenergie k\u00f6nnte dieser Anteil aber am Ende noch viel h\u00f6her ausfallen. Die polnische Regierung hat k\u00fcrzlich eine Erweiterung der Auktionen bis zum Jahr 2026 in Erw\u00e4gung gezogen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die starke Abh\u00e4ngigkeit des polnischen Stromsystems von der Kohlekraft und steigende Preise aufgrund der Kohlenstoffemissionen machen den Gro\u00dfhandelspreis f\u00fcr Strom in Polen zu einem der h\u00f6chsten in Europa. J\u00fcngste Entwicklungen zeigen daher auch, dass das Interesse an PPAs, also langfristigen Stromabnahmevertr\u00e4gen, im Land zugenommen hat. Das PPA-Gesch\u00e4ftsmodel, bei dem der Strom direkt vom Stromerzeuger Erneuerbarer Energien abgenommen wird und eine langfristige Stromversorgung f\u00fcr einen vorab vereinbarten Preis vertraglich festgelegt wird, entwickelt sich dabei zu einem attraktiven Gegenmodel au\u00dferhalb des nationalen F\u00f6rderprogramms.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auch Kunden der Nordex Group haben Auftr\u00e4ge \u00fcber die Lieferung von Anlagen des Typs N149\/4.0-4.5 der Delta4000-Serie f\u00fcr Projekte mit Stromabnahmevertr\u00e4gen bestellt. Die N149\/4.0\u20134.5 war die weltweit erste Turbine mit einer flexiblen Nennleistung als Teil der Design- und Betriebsstrategie. Dieser Designansatz in Kombination mit einer Vielzahl von Betriebsmodi erm\u00f6glicht es, jede Delta4000 an die individuellen Anforderungen des Netzbetreibers, an die lokalen Windverh\u00e4ltnisse und Schallvorgaben anzupassen. Dieser Flexibilit\u00e4tsansatz wurde mit der N149\/5.X und der N163\/5.X auf eine neue Ebene gehoben, so dass nun auch ein breites Spektrum an Leistungsmodi in der 5 MW+ Klasse abgedeckt werden kann.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Polen gilt wieder als interessanter Markt f\u00fcr Investoren und Entwicklern von Onshore-Windprojekten. Es ist davon auszugehen, dass die Attraktivit\u00e4t von PPA-Vertr\u00e4gen zunehmen wird und auch politisch k\u00f6nnte sich ein Umbruch entwickeln. Ein zus\u00e4tzlich wichtiger Schritt in der klimapolitischen Debatte des Landes ist auch die Diskussion um die 10H-Regelung, die seit 2016 besagt, dass der Mindestabstand von Windenergieanlagen zu Wohngeb\u00e4uden das 10-fache ihrer eigenen H\u00f6he betragen muss. Die polnische Regierung hat angek\u00fcndigt, diese restriktiven Vorschriften aufzuweichen und noch vor Ende 2020 Lockerungen zu ver\u00f6ffentlichen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Nordex Group ist bereits seit 2007 in Polen vertreten. Das Unternehmen besch\u00e4ftigt heute 48 Mitarbeiter im Land, die auf das lokale Hauptb\u00fcro in Warschau und neun Servicepoints verteilt sind. Die bisherige installierte Leistung an Onshore-Windenergie betr\u00e4gt mehr als 460 MW. Weitere 178 MW befinden sich derzeit vorwiegend mit Anlagentypen der Generation Delta, der vierten Generation der Nordex Multimegawatt-Plattform, im Bau. Nordex-Kunden profitieren bei diesen Anlagentypen von ausgereiften, technischen L\u00f6sungen, die sich tausendfach bew\u00e4hrt haben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Interesse an Erneuerbare Energien in Polen steigt. Mit einer breiten Produktpalette und flexiblen L\u00f6sungsans\u00e4tzen ist die Nordex Group bestens aufgestellt, um projektspezifische Anforderungen und individuelle Kundenbed\u00fcrfnisse zu erf\u00fcllen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>LOKALE ANSPRECHPARTNER DER NORDEX GROUP<\/strong><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>Michal Chojnacki<\/strong><br><strong>Managing Director Poland &amp; Romania, Head of Service East<\/strong><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>Norbert Dwenger<\/strong><br><strong>Vice President Sales Eastern Europe &amp; New Markets, Business Development<\/strong><\/p>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nachdem die Erneuerbaren Energien in Polen lange Zeit wenig Aufmerksamkeit in der Klima-Politik im Land hatten, setzt Polens Klimaministerium neue Akzente hin zu gr\u00fcnen Investitionen in der polnischen Energiewirtschaft. Polen, das seinen Energiebedarf \u00fcberwiegend mit fossilen Energietr\u00e4gern deckt, k\u00f6nnte damit vor einem Wendepunkt stehen und einen wichtigen Beitrag zur Energiewende leisten. Eine Schl\u00fcsselaufgabe wird dabei [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":4895,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_trash_the_other_posts":false,"editor_notices":[],"footnotes":""},"categories":[1249],"tags":[],"class_list":["post-4892","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-company-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>The Nordex Group around the world - Polen! - Nordex SE - Deutsch<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.nordex-online.com\/de\/2020\/08\/the-nordex-group-around-the-world-polen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Nordex Group around the world - Polen!\" \/>\n<meta property=\"og:description\" content=\"Nachdem die Erneuerbaren Energien in Polen lange Zeit wenig Aufmerksamkeit in der Klima-Politik im Land hatten, setzt Polens Klimaministerium neue Akzente hin zu gr\u00fcnen Investitionen in der polnischen Energiewirtschaft. Polen, das seinen Energiebedarf \u00fcberwiegend mit fossilen Energietr\u00e4gern deckt, k\u00f6nnte damit vor einem Wendepunkt stehen und einen wichtigen Beitrag zur Energiewende leisten. Eine Schl\u00fcsselaufgabe wird dabei [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nordex-online.com\/de\/2020\/08\/the-nordex-group-around-the-world-polen\/\" \/>\n<meta property=\"og:site_name\" content=\"Nordex SE - Deutsch\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-20T06:01:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-24T11:12:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.nordex-online.com\/wp-content\/uploads\/sites\/3\/2020\/08\/JOE150615_781_Kamionka-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1704\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Stege, Julia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Stege, Julia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2020\\\/08\\\/the-nordex-group-around-the-world-polen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2020\\\/08\\\/the-nordex-group-around-the-world-polen\\\/\"},\"author\":{\"name\":\"Stege, Julia\",\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/#\\\/schema\\\/person\\\/abae42d6c83dd3da6dcf7d89c0af02cd\"},\"headline\":\"The Nordex Group around the world &#8211; Polen!\",\"datePublished\":\"2020-08-20T06:01:04+00:00\",\"dateModified\":\"2023-04-24T11:12:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2020\\\/08\\\/the-nordex-group-around-the-world-polen\\\/\"},\"wordCount\":620,\"publisher\":{\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2020\\\/08\\\/the-nordex-group-around-the-world-polen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.nordex-online.com\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/08\\\/JOE150615_781_Kamionka-scaled.jpg\",\"articleSection\":[\"Unternehmensneuigkeiten\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2020\\\/08\\\/the-nordex-group-around-the-world-polen\\\/\",\"url\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2020\\\/08\\\/the-nordex-group-around-the-world-polen\\\/\",\"name\":\"The Nordex Group around the world - Polen! - Nordex SE - Deutsch\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2020\\\/08\\\/the-nordex-group-around-the-world-polen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2020\\\/08\\\/the-nordex-group-around-the-world-polen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.nordex-online.com\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/08\\\/JOE150615_781_Kamionka-scaled.jpg\",\"datePublished\":\"2020-08-20T06:01:04+00:00\",\"dateModified\":\"2023-04-24T11:12:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2020\\\/08\\\/the-nordex-group-around-the-world-polen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2020\\\/08\\\/the-nordex-group-around-the-world-polen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2020\\\/08\\\/the-nordex-group-around-the-world-polen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.nordex-online.com\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/08\\\/JOE150615_781_Kamionka-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.nordex-online.com\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/08\\\/JOE150615_781_Kamionka-scaled.jpg\",\"width\":2560,\"height\":1704,\"caption\":\"Windpark Kamionka in der Woiwodschaft Westpommern in Polen Kamionka wind farm in West Pommeranian in Poland. Wiindenergieanlagen\\\/turbines: 12 x Nordex N100 Gamma (2,5 MW) 15.6.2015 (c) Foto: Nordex SE \\\/ Jan Oelker , 2015 jan.oelker@gmx.de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2020\\\/08\\\/the-nordex-group-around-the-world-polen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The Nordex Group around the world &#8211; Polen!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/\",\"name\":\"Nordex SE - Deutsch\",\"description\":\"Manufacture, installation and maintenance of wind turbines.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/#organization\",\"name\":\"Nordex SE - Deutsch\",\"url\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.nordex-online.com\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/07\\\/cropped-cropped-cropped-Combined-Logos_cmyk_PNG.png\",\"contentUrl\":\"https:\\\/\\\/www.nordex-online.com\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/07\\\/cropped-cropped-cropped-Combined-Logos_cmyk_PNG.png\",\"width\":1181,\"height\":353,\"caption\":\"Nordex SE - Deutsch\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/#\\\/schema\\\/person\\\/abae42d6c83dd3da6dcf7d89c0af02cd\",\"name\":\"Stege, Julia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/414786f0498445e4645dd698dd8810a656a47d7789bca95094a9ee418a9b8a65?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/414786f0498445e4645dd698dd8810a656a47d7789bca95094a9ee418a9b8a65?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/414786f0498445e4645dd698dd8810a656a47d7789bca95094a9ee418a9b8a65?s=96&d=mm&r=g\",\"caption\":\"Stege, Julia\"},\"url\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/author\\\/jstege\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"The Nordex Group around the world - Polen! - Nordex SE - Deutsch","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.nordex-online.com\/de\/2020\/08\/the-nordex-group-around-the-world-polen\/","og_locale":"de_DE","og_type":"article","og_title":"The Nordex Group around the world - Polen!","og_description":"Nachdem die Erneuerbaren Energien in Polen lange Zeit wenig Aufmerksamkeit in der Klima-Politik im Land hatten, setzt Polens Klimaministerium neue Akzente hin zu gr\u00fcnen Investitionen in der polnischen Energiewirtschaft. Polen, das seinen Energiebedarf \u00fcberwiegend mit fossilen Energietr\u00e4gern deckt, k\u00f6nnte damit vor einem Wendepunkt stehen und einen wichtigen Beitrag zur Energiewende leisten. Eine Schl\u00fcsselaufgabe wird dabei [&hellip;]","og_url":"https:\/\/www.nordex-online.com\/de\/2020\/08\/the-nordex-group-around-the-world-polen\/","og_site_name":"Nordex SE - Deutsch","article_published_time":"2020-08-20T06:01:04+00:00","article_modified_time":"2023-04-24T11:12:28+00:00","og_image":[{"width":2560,"height":1704,"url":"https:\/\/www.nordex-online.com\/wp-content\/uploads\/sites\/3\/2020\/08\/JOE150615_781_Kamionka-scaled.jpg","type":"image\/jpeg"}],"author":"Stege, Julia","twitter_card":"summary_large_image","twitter_misc":{"Geschrieben von":"Stege, Julia","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.nordex-online.com\/de\/2020\/08\/the-nordex-group-around-the-world-polen\/#article","isPartOf":{"@id":"https:\/\/www.nordex-online.com\/de\/2020\/08\/the-nordex-group-around-the-world-polen\/"},"author":{"name":"Stege, Julia","@id":"https:\/\/www.nordex-online.com\/de\/#\/schema\/person\/abae42d6c83dd3da6dcf7d89c0af02cd"},"headline":"The Nordex Group around the world &#8211; Polen!","datePublished":"2020-08-20T06:01:04+00:00","dateModified":"2023-04-24T11:12:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.nordex-online.com\/de\/2020\/08\/the-nordex-group-around-the-world-polen\/"},"wordCount":620,"publisher":{"@id":"https:\/\/www.nordex-online.com\/de\/#organization"},"image":{"@id":"https:\/\/www.nordex-online.com\/de\/2020\/08\/the-nordex-group-around-the-world-polen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.nordex-online.com\/wp-content\/uploads\/sites\/3\/2020\/08\/JOE150615_781_Kamionka-scaled.jpg","articleSection":["Unternehmensneuigkeiten"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.nordex-online.com\/de\/2020\/08\/the-nordex-group-around-the-world-polen\/","url":"https:\/\/www.nordex-online.com\/de\/2020\/08\/the-nordex-group-around-the-world-polen\/","name":"The Nordex Group around the world - Polen! - Nordex SE - Deutsch","isPartOf":{"@id":"https:\/\/www.nordex-online.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.nordex-online.com\/de\/2020\/08\/the-nordex-group-around-the-world-polen\/#primaryimage"},"image":{"@id":"https:\/\/www.nordex-online.com\/de\/2020\/08\/the-nordex-group-around-the-world-polen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.nordex-online.com\/wp-content\/uploads\/sites\/3\/2020\/08\/JOE150615_781_Kamionka-scaled.jpg","datePublished":"2020-08-20T06:01:04+00:00","dateModified":"2023-04-24T11:12:28+00:00","breadcrumb":{"@id":"https:\/\/www.nordex-online.com\/de\/2020\/08\/the-nordex-group-around-the-world-polen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.nordex-online.com\/de\/2020\/08\/the-nordex-group-around-the-world-polen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.nordex-online.com\/de\/2020\/08\/the-nordex-group-around-the-world-polen\/#primaryimage","url":"https:\/\/www.nordex-online.com\/wp-content\/uploads\/sites\/3\/2020\/08\/JOE150615_781_Kamionka-scaled.jpg","contentUrl":"https:\/\/www.nordex-online.com\/wp-content\/uploads\/sites\/3\/2020\/08\/JOE150615_781_Kamionka-scaled.jpg","width":2560,"height":1704,"caption":"Windpark Kamionka in der Woiwodschaft Westpommern in Polen Kamionka wind farm in West Pommeranian in Poland. Wiindenergieanlagen\/turbines: 12 x Nordex N100 Gamma (2,5 MW) 15.6.2015 (c) Foto: Nordex SE \/ Jan Oelker , 2015 jan.oelker@gmx.de"},{"@type":"BreadcrumbList","@id":"https:\/\/www.nordex-online.com\/de\/2020\/08\/the-nordex-group-around-the-world-polen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.nordex-online.com\/de\/"},{"@type":"ListItem","position":2,"name":"The Nordex Group around the world &#8211; Polen!"}]},{"@type":"WebSite","@id":"https:\/\/www.nordex-online.com\/de\/#website","url":"https:\/\/www.nordex-online.com\/de\/","name":"Nordex SE - Deutsch","description":"Manufacture, installation and maintenance of wind turbines.","publisher":{"@id":"https:\/\/www.nordex-online.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nordex-online.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.nordex-online.com\/de\/#organization","name":"Nordex SE - Deutsch","url":"https:\/\/www.nordex-online.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.nordex-online.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.nordex-online.com\/wp-content\/uploads\/sites\/3\/2024\/07\/cropped-cropped-cropped-Combined-Logos_cmyk_PNG.png","contentUrl":"https:\/\/www.nordex-online.com\/wp-content\/uploads\/sites\/3\/2024\/07\/cropped-cropped-cropped-Combined-Logos_cmyk_PNG.png","width":1181,"height":353,"caption":"Nordex SE - Deutsch"},"image":{"@id":"https:\/\/www.nordex-online.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.nordex-online.com\/de\/#\/schema\/person\/abae42d6c83dd3da6dcf7d89c0af02cd","name":"Stege, Julia","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/414786f0498445e4645dd698dd8810a656a47d7789bca95094a9ee418a9b8a65?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/414786f0498445e4645dd698dd8810a656a47d7789bca95094a9ee418a9b8a65?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/414786f0498445e4645dd698dd8810a656a47d7789bca95094a9ee418a9b8a65?s=96&d=mm&r=g","caption":"Stege, Julia"},"url":"https:\/\/www.nordex-online.com\/de\/author\/jstege\/"}]}},"_links":{"self":[{"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/posts\/4892","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/comments?post=4892"}],"version-history":[{"count":8,"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/posts\/4892\/revisions"}],"predecessor-version":[{"id":4901,"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/posts\/4892\/revisions\/4901"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/media\/4895"}],"wp:attachment":[{"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/media?parent=4892"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/categories?post=4892"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/tags?post=4892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}