{"id":46025,"date":"2022-09-16T17:19:14","date_gmt":"2022-09-16T17:19:14","guid":{"rendered":"https:\/\/www.nordex-online.com\/de\/2022\/09\/nordex-se-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-verschmelzung-der-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-auf-die-momentum-beteiligungsgesellschaft-mbh-die-momentum\/"},"modified":"2026-05-13T09:06:28","modified_gmt":"2026-05-13T09:06:28","slug":"nordex-se-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-verschmelzung-der-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-auf-die-momentum-beteiligungsgesellschaft-mbh-die-momentum","status":"publish","type":"post","link":"https:\/\/www.nordex-online.com\/de\/2022\/09\/nordex-se-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-verschmelzung-der-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-auf-die-momentum-beteiligungsgesellschaft-mbh-die-momentum\/","title":{"rendered":"Nordex SE: momentum-capital Verm\u00f6gensverwaltungsgesellschaft mbH, Verschmelzung der momentum-capital Verm\u00f6gensverwaltungsgesellschaft mbH auf die momentum Beteiligungsgesellschaft mbH.\nDie momentum-capital Verm\u00f6gensverwaltungsgesellschaft ist die abgebende Gesellschaft."},"content":{"rendered":"<table border=\"0\">\n<tr>\n<td>\n<p><\/p>\n<p>Meldung und \u00f6ffentliche Bekanntgabe der Gesch\u00e4fte von Personen, die F\u00fchrungsaufgaben wahrnehmen, sowie in enger Beziehung zu ihnen stehenden Personen <\/p>\n<p>16.09.2022 \/ 19:18 CET\/CEST<\/p>\n<p>F\u00fcr den Inhalt der Mitteilung ist der Emittent \/ Herausgeber verantwortlich.<\/p>\n<hr \/>\n<div>\n<p><strong>1. Angaben zu den Personen, die F\u00fchrungsaufgaben wahrnehmen, sowie zu den in enger Beziehung zu ihnen stehenden Personen<\/strong><\/p>\n<p>a) Name<\/p>\n<table border=\"1\">\n<tr>\n<td>Name und Rechtsform:<\/td>\n<td>momentum-capital Verm\u00f6gensverwaltungsgesellschaft mbH<\/td>\n<\/tr>\n<\/table>\n<p><strong>2. Grund der Meldung<\/strong><\/p>\n<p>a) Position \/ Status<\/p>\n<table border=\"1\">\n<tr>\n<td colspan=\"2\">Person steht in enger Beziehung zu:<\/td>\n<\/tr>\n<tr>\n<td>Titel:<\/td>\n<td \/>\n<\/tr>\n<tr>\n<td>Vorname:<\/td>\n<td>Jan<\/td>\n<\/tr>\n<tr>\n<td>Nachname(n):<\/td>\n<td>Klatten<\/td>\n<\/tr>\n<tr>\n<td>Position:<\/td>\n<td>Aufsichtsrat<\/td>\n<\/tr>\n<\/table>\n<p><\/p>\n<p>b) Erstmeldung<\/p>\n<p><strong>3. Angaben zum Emittenten, zum Teilnehmer am Markt f\u00fcr Emissionszertifikate, zur Versteigerungsplattform, zum Versteigerer oder zur Auktionsaufsicht<\/strong><\/p>\n<p>a) Name<\/p>\n<table border=\"1\">\n<tr>\n<td>Nordex SE<\/td>\n<\/tr>\n<\/table>\n<p>\nb) LEI<\/p>\n<table border=\"1\">\n<tr>\n<td>529900HVDYCUWVD0OE76\u00a0<\/td>\n<\/tr>\n<\/table>\n<p><strong>4. Angaben zum Gesch\u00e4ft\/zu den Gesch\u00e4ften<\/strong><\/p>\n<p>a) Beschreibung des Finanzinstruments, Art des Instruments, Kennung<\/p>\n<table border=\"1\">\n<tr>\n<td>Art:<\/td>\n<td>Aktie<\/td>\n<\/tr>\n<tr>\n<td>ISIN:<\/td>\n<td>DE000A0D6554<\/td>\n<\/tr>\n<\/table>\n<p>\nb) Art des Gesch\u00e4fts<\/p>\n<table border=\"1\">\n<tr>\n<td>Verschmelzung der momentum-capital Verm\u00f6gensverwaltungsgesellschaft mbH auf die momentum Beteiligungsgesellschaft mbH.<br \/>\nDie momentum-capital Verm\u00f6gensverwaltungsgesellschaft ist die abgebende Gesellschaft.<\/td>\n<\/tr>\n<\/table>\n<p>\nc) Preis(e) und Volumen<\/p>\n<table border=\"1\">\n<tr>\n<td>Preis(e)<\/td>\n<td>Volumen<\/td>\n<\/tr>\n<tr>\n<td>2.80 EUR<\/td>\n<td>1366221.80 EUR<\/td>\n<\/tr>\n<\/table>\n<p>\nd) Aggregierte Informationen<\/p>\n<table border=\"1\">\n<tr>\n<td>Preis<\/td>\n<td>Aggregiertes Volumen<\/td>\n<\/tr>\n<tr>\n<td>2.80 EUR<\/td>\n<td>1366221.80 EUR<\/td>\n<\/tr>\n<\/table>\n<p>\ne) Datum des Gesch\u00e4fts<\/p>\n<table border=\"1\">\n<tr>\n<td>29.06.2022; UTC+2<\/td>\n<\/tr>\n<\/table>\n<p>\nf) Ort des Gesch\u00e4fts<\/p>\n<table border=\"1\">\n<tr>\n<td>Au\u00dferhalb eines Handelsplatzes<\/td>\n<\/tr>\n<\/table>\n<p><\/div>\n<p><\/p>\n<hr \/>\n<p>\n16.09.2022 CET\/CEST Die DGAP Distributionsservices umfassen gesetzliche Meldepflichten, Corporate News\/Finanznachrichten und Pressemitteilungen.<br \/>Medienarchiv unter http:\/\/www.dgap.de<\/p>\n<hr \/>\n<\/td>\n<\/tr>\n<\/table>\n<table>\n<tr>\n<td align=\"left\" valign=\"top\">Sprache:<\/td>\n<td align=\"left\" valign=\"top\">Deutsch<\/td>\n<\/tr>\n<tr>\n<td align=\"left\" valign=\"top\">Unternehmen:<\/td>\n<td align=\"left\" valign=\"top\">Nordex SE<\/td>\n<\/tr>\n<tr>\n<td align=\"left\" valign=\"top\" \/>\n<td align=\"left\" valign=\"top\">Erich-Schlesinger-Stra\u00dfe 50<\/td>\n<\/tr>\n<tr>\n<td align=\"left\" valign=\"top\" \/>\n<td align=\"left\" valign=\"top\">18059 Rostock<\/td>\n<\/tr>\n<tr>\n<td align=\"left\" valign=\"top\" \/>\n<td align=\"left\" valign=\"top\">Deutschland<\/td>\n<\/tr>\n<tr>\n<td align=\"left\" valign=\"top\">Internet:<\/td>\n<td align=\"left\" valign=\"top\">www.nordex-online.com<\/td>\n<\/tr>\n<\/table>\n<p><\/p>\n<table border=\"0\">\n<tr>\n<td align=\"left\" valign=\"top\" colspan=\"2\" \/>\n<\/tr>\n<\/table>\n<table border=\"0\">\n<tr>\n<td align=\"left\" valign=\"top\" colspan=\"2\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td align=\"left\" valign=\"top\">Ende der Mitteilung<\/td>\n<td align=\"left\" valign=\"top\">DGAP News-Service<\/td>\n<\/tr>\n<\/table>\n<table border=\"0\">\n<tr>\n<td>\n<hr \/>\n<\/td>\n<\/tr>\n<\/table>\n<p>\n78249\u00a0\u00a016.09.2022\u00a0CET\/CEST<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/eqs-cockpit.com\/cgi-bin\/fncls.ssp?fn=show_t_gif&amp;application_id=1444735&amp;application_name=news&amp;site_id=airport_aws\" alt=\"fncls.ssp?fn=show_t_gif&amp;application_id=1444735&amp;application_name=news&amp;site_id=airport_aws\" width=\"0\" height=\"0\" border=\"0\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Meldung und \u00f6ffentliche Bekanntgabe der Gesch\u00e4fte von Personen, die F\u00fchrungsaufgaben wahrnehmen, sowie in enger Beziehung zu ihnen stehenden Personen 16.09.2022 \/ 19:18 CET\/CEST F\u00fcr den Inhalt der Mitteilung ist der Emittent \/ Herausgeber verantwortlich. 1. Angaben zu den Personen, die F\u00fchrungsaufgaben wahrnehmen, sowie zu den in enger Beziehung zu ihnen stehenden Personen a) Name Name [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_trash_the_other_posts":false,"editor_notices":[],"footnotes":""},"categories":[1253,1250],"tags":[],"class_list":["post-46025","post","type-post","status-publish","format-standard","hentry","category-directors-dealings-managers-transactions","category-investor-relations"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Nordex SE: momentum-capital Verm\u00f6gensverwaltungsgesellschaft mbH, Verschmelzung der momentum-capital Verm\u00f6gensverwaltungsgesellschaft mbH auf die momentum Beteiligungsgesellschaft mbH. Die momentum-capital Verm\u00f6gensverwaltungsgesellschaft ist die abgebende Gesellschaft. - Nordex SE - Deutsch<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.nordex-online.com\/de\/2022\/09\/nordex-se-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-verschmelzung-der-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-auf-die-momentum-beteiligungsgesellschaft-mbh-die-momentum\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nordex SE: momentum-capital Verm\u00f6gensverwaltungsgesellschaft mbH, Verschmelzung der momentum-capital Verm\u00f6gensverwaltungsgesellschaft mbH auf die momentum Beteiligungsgesellschaft mbH. Die momentum-capital Verm\u00f6gensverwaltungsgesellschaft ist die abgebende Gesellschaft.\" \/>\n<meta property=\"og:description\" content=\"Meldung und \u00f6ffentliche Bekanntgabe der Gesch\u00e4fte von Personen, die F\u00fchrungsaufgaben wahrnehmen, sowie in enger Beziehung zu ihnen stehenden Personen 16.09.2022 \/ 19:18 CET\/CEST F\u00fcr den Inhalt der Mitteilung ist der Emittent \/ Herausgeber verantwortlich. 1. Angaben zu den Personen, die F\u00fchrungsaufgaben wahrnehmen, sowie zu den in enger Beziehung zu ihnen stehenden Personen a) Name Name [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nordex-online.com\/de\/2022\/09\/nordex-se-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-verschmelzung-der-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-auf-die-momentum-beteiligungsgesellschaft-mbh-die-momentum\/\" \/>\n<meta property=\"og:site_name\" content=\"Nordex SE - Deutsch\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-16T17:19:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T09:06:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eqs-cockpit.com\/cgi-bin\/fncls.ssp?fn=show_t_gif&amp;application_id=1444735&amp;application_name=news&amp;site_id=airport_aws\" \/>\n<meta name=\"author\" content=\"aeckert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"aeckert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2022\\\/09\\\/nordex-se-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-verschmelzung-der-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-auf-die-momentum-beteiligungsgesellschaft-mbh-die-momentum\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2022\\\/09\\\/nordex-se-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-verschmelzung-der-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-auf-die-momentum-beteiligungsgesellschaft-mbh-die-momentum\\\/\"},\"author\":{\"name\":\"aeckert\",\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/#\\\/schema\\\/person\\\/81621b8f0d2d2d605ac828cef137de95\"},\"headline\":\"Nordex SE: momentum-capital Verm\u00f6gensverwaltungsgesellschaft mbH, Verschmelzung der momentum-capital Verm\u00f6gensverwaltungsgesellschaft mbH auf die momentum Beteiligungsgesellschaft mbH. Die momentum-capital Verm\u00f6gensverwaltungsgesellschaft ist die abgebende Gesellschaft.\",\"datePublished\":\"2022-09-16T17:19:14+00:00\",\"dateModified\":\"2026-05-13T09:06:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2022\\\/09\\\/nordex-se-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-verschmelzung-der-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-auf-die-momentum-beteiligungsgesellschaft-mbh-die-momentum\\\/\"},\"wordCount\":251,\"publisher\":{\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2022\\\/09\\\/nordex-se-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-verschmelzung-der-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-auf-die-momentum-beteiligungsgesellschaft-mbh-die-momentum\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eqs-cockpit.com\\\/cgi-bin\\\/fncls.ssp?fn=show_t_gif&amp;application_id=1444735&amp;application_name=news&amp;site_id=airport_aws\",\"articleSection\":[\"Directors\u2019 Dealings \\\/ Managers\u2019 Transactions\",\"Investorenbeziehungen\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2022\\\/09\\\/nordex-se-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-verschmelzung-der-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-auf-die-momentum-beteiligungsgesellschaft-mbh-die-momentum\\\/\",\"url\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2022\\\/09\\\/nordex-se-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-verschmelzung-der-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-auf-die-momentum-beteiligungsgesellschaft-mbh-die-momentum\\\/\",\"name\":\"Nordex SE: momentum-capital Verm\u00f6gensverwaltungsgesellschaft mbH, Verschmelzung der momentum-capital Verm\u00f6gensverwaltungsgesellschaft mbH auf die momentum Beteiligungsgesellschaft mbH. Die momentum-capital Verm\u00f6gensverwaltungsgesellschaft ist die abgebende Gesellschaft. - Nordex SE - Deutsch\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2022\\\/09\\\/nordex-se-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-verschmelzung-der-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-auf-die-momentum-beteiligungsgesellschaft-mbh-die-momentum\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2022\\\/09\\\/nordex-se-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-verschmelzung-der-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-auf-die-momentum-beteiligungsgesellschaft-mbh-die-momentum\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eqs-cockpit.com\\\/cgi-bin\\\/fncls.ssp?fn=show_t_gif&amp;application_id=1444735&amp;application_name=news&amp;site_id=airport_aws\",\"datePublished\":\"2022-09-16T17:19:14+00:00\",\"dateModified\":\"2026-05-13T09:06:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2022\\\/09\\\/nordex-se-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-verschmelzung-der-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-auf-die-momentum-beteiligungsgesellschaft-mbh-die-momentum\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2022\\\/09\\\/nordex-se-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-verschmelzung-der-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-auf-die-momentum-beteiligungsgesellschaft-mbh-die-momentum\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2022\\\/09\\\/nordex-se-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-verschmelzung-der-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-auf-die-momentum-beteiligungsgesellschaft-mbh-die-momentum\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eqs-cockpit.com\\\/cgi-bin\\\/fncls.ssp?fn=show_t_gif&amp;application_id=1444735&amp;application_name=news&amp;site_id=airport_aws\",\"contentUrl\":\"https:\\\/\\\/eqs-cockpit.com\\\/cgi-bin\\\/fncls.ssp?fn=show_t_gif&amp;application_id=1444735&amp;application_name=news&amp;site_id=airport_aws\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2022\\\/09\\\/nordex-se-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-verschmelzung-der-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-auf-die-momentum-beteiligungsgesellschaft-mbh-die-momentum\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nordex SE: momentum-capital Verm\u00f6gensverwaltungsgesellschaft mbH, Verschmelzung der momentum-capital Verm\u00f6gensverwaltungsgesellschaft mbH auf die momentum Beteiligungsgesellschaft mbH. Die momentum-capital Verm\u00f6gensverwaltungsgesellschaft ist die abgebende Gesellschaft.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/\",\"name\":\"Nordex SE - Deutsch\",\"description\":\"Manufacture, installation and maintenance of wind turbines.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/#organization\",\"name\":\"Nordex SE - Deutsch\",\"url\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.nordex-online.com\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/07\\\/cropped-cropped-Combined-Logos_cmyk_PNG.png\",\"contentUrl\":\"https:\\\/\\\/www.nordex-online.com\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/07\\\/cropped-cropped-Combined-Logos_cmyk_PNG.png\",\"width\":1181,\"height\":353,\"caption\":\"Nordex SE - Deutsch\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/#\\\/schema\\\/person\\\/81621b8f0d2d2d605ac828cef137de95\",\"name\":\"aeckert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9bb1da8fdca865f8714afd486408f3f4d26ef53f3ff2e44201e2a0a3b5e3c6b2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9bb1da8fdca865f8714afd486408f3f4d26ef53f3ff2e44201e2a0a3b5e3c6b2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9bb1da8fdca865f8714afd486408f3f4d26ef53f3ff2e44201e2a0a3b5e3c6b2?s=96&d=mm&r=g\",\"caption\":\"aeckert\"},\"url\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/author\\\/antje\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Nordex SE: momentum-capital Verm\u00f6gensverwaltungsgesellschaft mbH, Verschmelzung der momentum-capital Verm\u00f6gensverwaltungsgesellschaft mbH auf die momentum Beteiligungsgesellschaft mbH. Die momentum-capital Verm\u00f6gensverwaltungsgesellschaft ist die abgebende Gesellschaft. - Nordex SE - Deutsch","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.nordex-online.com\/de\/2022\/09\/nordex-se-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-verschmelzung-der-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-auf-die-momentum-beteiligungsgesellschaft-mbh-die-momentum\/","og_locale":"de_DE","og_type":"article","og_title":"Nordex SE: momentum-capital Verm\u00f6gensverwaltungsgesellschaft mbH, Verschmelzung der momentum-capital Verm\u00f6gensverwaltungsgesellschaft mbH auf die momentum Beteiligungsgesellschaft mbH. Die momentum-capital Verm\u00f6gensverwaltungsgesellschaft ist die abgebende Gesellschaft.","og_description":"Meldung und \u00f6ffentliche Bekanntgabe der Gesch\u00e4fte von Personen, die F\u00fchrungsaufgaben wahrnehmen, sowie in enger Beziehung zu ihnen stehenden Personen 16.09.2022 \/ 19:18 CET\/CEST F\u00fcr den Inhalt der Mitteilung ist der Emittent \/ Herausgeber verantwortlich. 1. Angaben zu den Personen, die F\u00fchrungsaufgaben wahrnehmen, sowie zu den in enger Beziehung zu ihnen stehenden Personen a) Name Name [&hellip;]","og_url":"https:\/\/www.nordex-online.com\/de\/2022\/09\/nordex-se-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-verschmelzung-der-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-auf-die-momentum-beteiligungsgesellschaft-mbh-die-momentum\/","og_site_name":"Nordex SE - Deutsch","article_published_time":"2022-09-16T17:19:14+00:00","article_modified_time":"2026-05-13T09:06:28+00:00","og_image":[{"url":"https:\/\/eqs-cockpit.com\/cgi-bin\/fncls.ssp?fn=show_t_gif&amp;application_id=1444735&amp;application_name=news&amp;site_id=airport_aws","type":"","width":"","height":""}],"author":"aeckert","twitter_card":"summary_large_image","twitter_misc":{"Geschrieben von":"aeckert","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.nordex-online.com\/de\/2022\/09\/nordex-se-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-verschmelzung-der-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-auf-die-momentum-beteiligungsgesellschaft-mbh-die-momentum\/#article","isPartOf":{"@id":"https:\/\/www.nordex-online.com\/de\/2022\/09\/nordex-se-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-verschmelzung-der-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-auf-die-momentum-beteiligungsgesellschaft-mbh-die-momentum\/"},"author":{"name":"aeckert","@id":"https:\/\/www.nordex-online.com\/de\/#\/schema\/person\/81621b8f0d2d2d605ac828cef137de95"},"headline":"Nordex SE: momentum-capital Verm\u00f6gensverwaltungsgesellschaft mbH, Verschmelzung der momentum-capital Verm\u00f6gensverwaltungsgesellschaft mbH auf die momentum Beteiligungsgesellschaft mbH. Die momentum-capital Verm\u00f6gensverwaltungsgesellschaft ist die abgebende Gesellschaft.","datePublished":"2022-09-16T17:19:14+00:00","dateModified":"2026-05-13T09:06:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.nordex-online.com\/de\/2022\/09\/nordex-se-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-verschmelzung-der-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-auf-die-momentum-beteiligungsgesellschaft-mbh-die-momentum\/"},"wordCount":251,"publisher":{"@id":"https:\/\/www.nordex-online.com\/de\/#organization"},"image":{"@id":"https:\/\/www.nordex-online.com\/de\/2022\/09\/nordex-se-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-verschmelzung-der-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-auf-die-momentum-beteiligungsgesellschaft-mbh-die-momentum\/#primaryimage"},"thumbnailUrl":"https:\/\/eqs-cockpit.com\/cgi-bin\/fncls.ssp?fn=show_t_gif&amp;application_id=1444735&amp;application_name=news&amp;site_id=airport_aws","articleSection":["Directors\u2019 Dealings \/ Managers\u2019 Transactions","Investorenbeziehungen"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.nordex-online.com\/de\/2022\/09\/nordex-se-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-verschmelzung-der-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-auf-die-momentum-beteiligungsgesellschaft-mbh-die-momentum\/","url":"https:\/\/www.nordex-online.com\/de\/2022\/09\/nordex-se-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-verschmelzung-der-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-auf-die-momentum-beteiligungsgesellschaft-mbh-die-momentum\/","name":"Nordex SE: momentum-capital Verm\u00f6gensverwaltungsgesellschaft mbH, Verschmelzung der momentum-capital Verm\u00f6gensverwaltungsgesellschaft mbH auf die momentum Beteiligungsgesellschaft mbH. Die momentum-capital Verm\u00f6gensverwaltungsgesellschaft ist die abgebende Gesellschaft. - Nordex SE - Deutsch","isPartOf":{"@id":"https:\/\/www.nordex-online.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.nordex-online.com\/de\/2022\/09\/nordex-se-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-verschmelzung-der-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-auf-die-momentum-beteiligungsgesellschaft-mbh-die-momentum\/#primaryimage"},"image":{"@id":"https:\/\/www.nordex-online.com\/de\/2022\/09\/nordex-se-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-verschmelzung-der-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-auf-die-momentum-beteiligungsgesellschaft-mbh-die-momentum\/#primaryimage"},"thumbnailUrl":"https:\/\/eqs-cockpit.com\/cgi-bin\/fncls.ssp?fn=show_t_gif&amp;application_id=1444735&amp;application_name=news&amp;site_id=airport_aws","datePublished":"2022-09-16T17:19:14+00:00","dateModified":"2026-05-13T09:06:28+00:00","breadcrumb":{"@id":"https:\/\/www.nordex-online.com\/de\/2022\/09\/nordex-se-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-verschmelzung-der-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-auf-die-momentum-beteiligungsgesellschaft-mbh-die-momentum\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.nordex-online.com\/de\/2022\/09\/nordex-se-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-verschmelzung-der-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-auf-die-momentum-beteiligungsgesellschaft-mbh-die-momentum\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.nordex-online.com\/de\/2022\/09\/nordex-se-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-verschmelzung-der-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-auf-die-momentum-beteiligungsgesellschaft-mbh-die-momentum\/#primaryimage","url":"https:\/\/eqs-cockpit.com\/cgi-bin\/fncls.ssp?fn=show_t_gif&amp;application_id=1444735&amp;application_name=news&amp;site_id=airport_aws","contentUrl":"https:\/\/eqs-cockpit.com\/cgi-bin\/fncls.ssp?fn=show_t_gif&amp;application_id=1444735&amp;application_name=news&amp;site_id=airport_aws"},{"@type":"BreadcrumbList","@id":"https:\/\/www.nordex-online.com\/de\/2022\/09\/nordex-se-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-verschmelzung-der-momentum-capital-vermoegensverwaltungsgesellschaft-mbh-auf-die-momentum-beteiligungsgesellschaft-mbh-die-momentum\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.nordex-online.com\/de\/"},{"@type":"ListItem","position":2,"name":"Nordex SE: momentum-capital Verm\u00f6gensverwaltungsgesellschaft mbH, Verschmelzung der momentum-capital Verm\u00f6gensverwaltungsgesellschaft mbH auf die momentum Beteiligungsgesellschaft mbH. Die momentum-capital Verm\u00f6gensverwaltungsgesellschaft ist die abgebende Gesellschaft."}]},{"@type":"WebSite","@id":"https:\/\/www.nordex-online.com\/de\/#website","url":"https:\/\/www.nordex-online.com\/de\/","name":"Nordex SE - Deutsch","description":"Manufacture, installation and maintenance of wind turbines.","publisher":{"@id":"https:\/\/www.nordex-online.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nordex-online.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.nordex-online.com\/de\/#organization","name":"Nordex SE - Deutsch","url":"https:\/\/www.nordex-online.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.nordex-online.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.nordex-online.com\/wp-content\/uploads\/sites\/3\/2024\/07\/cropped-cropped-Combined-Logos_cmyk_PNG.png","contentUrl":"https:\/\/www.nordex-online.com\/wp-content\/uploads\/sites\/3\/2024\/07\/cropped-cropped-Combined-Logos_cmyk_PNG.png","width":1181,"height":353,"caption":"Nordex SE - Deutsch"},"image":{"@id":"https:\/\/www.nordex-online.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.nordex-online.com\/de\/#\/schema\/person\/81621b8f0d2d2d605ac828cef137de95","name":"aeckert","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/9bb1da8fdca865f8714afd486408f3f4d26ef53f3ff2e44201e2a0a3b5e3c6b2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9bb1da8fdca865f8714afd486408f3f4d26ef53f3ff2e44201e2a0a3b5e3c6b2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9bb1da8fdca865f8714afd486408f3f4d26ef53f3ff2e44201e2a0a3b5e3c6b2?s=96&d=mm&r=g","caption":"aeckert"},"url":"https:\/\/www.nordex-online.com\/de\/author\/antje\/"}]}},"_links":{"self":[{"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/posts\/46025","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/comments?post=46025"}],"version-history":[{"count":1,"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/posts\/46025\/revisions"}],"predecessor-version":[{"id":46026,"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/posts\/46025\/revisions\/46026"}],"wp:attachment":[{"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/media?parent=46025"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/categories?post=46025"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/tags?post=46025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}