{"id":40606,"date":"2023-10-27T09:14:33","date_gmt":"2023-10-27T09:14:33","guid":{"rendered":"https:\/\/www.nordex-online.com\/de\/2023\/10\/nordex-se-veroeffentlichung-gemaess-%c2%a7-40-abs-1-wphg-mit-dem-ziel-der-europaweiten-verbreitung-223\/"},"modified":"2025-08-14T06:43:55","modified_gmt":"2025-08-14T06:43:55","slug":"nordex-se-veroeffentlichung-gemaess-%c2%a7-40-abs-1-wphg-mit-dem-ziel-der-europaweiten-verbreitung-223","status":"publish","type":"post","link":"https:\/\/www.nordex-online.com\/de\/2023\/10\/nordex-se-veroeffentlichung-gemaess-%c2%a7-40-abs-1-wphg-mit-dem-ziel-der-europaweiten-verbreitung-223\/","title":{"rendered":"UBS Group AG, Z\u00fcrich, Schweiz"},"content":{"rendered":"<table border=\"0\">\n<tr>\n<td>\n<p>Nordex SE<\/p>\n<p><\/p>\n<p>Nordex SE: Ver\u00f6ffentlichung gem\u00e4\u00df \u00a7 40 Abs. 1 WpHG mit dem Ziel der europaweiten Verbreitung <\/p>\n<p>27.10.2023 \/ 11:14 CET\/CEST<\/p>\n<p>Ver\u00f6ffentlichung einer Stimmrechtsmitteilung \u00fcbermittelt durch EQS News &#8211; ein Service der EQS Group AG.<\/p>\n<p>F\u00fcr den Inhalt der Mitteilung ist der Emittent \/ Herausgeber verantwortlich.<\/p>\n<hr \/>\n<div>\n<strong>Stimmrechtsmitteilung<\/strong><\/p>\n<p><strong>1. Angaben zum Emittenten<\/strong><\/p>\n<table border=\"1\">\n<tr>\n<td>Name:<\/td>\n<td>Nordex SE<\/td>\n<\/tr>\n<tr>\n<td>Stra\u00dfe, Hausnr.:<\/td>\n<td>Erich-Schlesinger-Stra\u00dfe 50<\/td>\n<\/tr>\n<tr>\n<td>PLZ:<\/td>\n<td>18059<\/td>\n<\/tr>\n<tr>\n<td>Ort:<\/td>\n<td>Rostock<br \/>Deutschland<\/td>\n<\/tr>\n<tr>\n<td>Legal Entity Identifier (LEI):<\/td>\n<td>529900HVDYCUWVD0OE76<\/td>\n<\/tr>\n<\/table>\n<p><strong>2. Grund der Mitteilung<\/strong><\/p>\n<table border=\"1\">\n<tr>\n<td>X<\/td>\n<td>Erwerb bzw. Ver\u00e4u\u00dferung von Aktien mit Stimmrechten<\/td>\n<\/tr>\n<tr>\n<td>\u00a0<\/td>\n<td>Erwerb bzw. Ver\u00e4u\u00dferung von Instrumenten<\/td>\n<\/tr>\n<tr>\n<td>\u00a0<\/td>\n<td>\u00c4nderung der Gesamtzahl der Stimmrechte<\/td>\n<\/tr>\n<tr>\n<td>\u00a0<\/td>\n<td>Sonstiger Grund:<\/td>\n<\/tr>\n<\/table>\n<p><strong>3. Angaben zum Mitteilungspflichtigen<\/strong><\/p>\n<table border=\"1\">\n<tr>\n<td>Juristische Person: UBS Group AG<br \/>Registrierter Sitz, Staat: Z\u00fcrich, Schweiz<\/td>\n<\/tr>\n<\/table>\n<p><strong>4. Namen der Aktion\u00e4re<\/strong><br \/>\nmit 3% oder mehr Stimmrechten, wenn abweichend von 3.<\/p>\n<table border=\"1\">\n<tr>\n<td>UBS AG<\/td>\n<\/tr>\n<\/table>\n<p><strong>5. Datum der Schwellenber\u00fchrung:<\/strong><\/p>\n<table border=\"1\">\n<tr>\n<td>20.10.2023<\/td>\n<\/tr>\n<\/table>\n<p><strong>6. Gesamtstimmrechtsanteile<\/strong><\/p>\n<table border=\"1\">\n<tr>\n<td>\u00a0<\/td>\n<td align=\"right\">Anteil Stimmrechte <br \/>(Summe 7.a.)<\/td>\n<td align=\"right\">Anteil Instrumente <br \/>(Summe 7.b.1.+ 7.b.2.)<\/td>\n<td align=\"right\">Summe Anteile <br \/>(Summe 7.a. + 7.b.)<\/td>\n<td align=\"right\">Gesamtzahl der Stimmrechte nach \u00a7 41 WpHG<\/td>\n<\/tr>\n<tr>\n<td>neu<\/td>\n<td align=\"right\">5,19 %<\/td>\n<td align=\"right\">2,17 %<\/td>\n<td align=\"right\">7,37 %<\/td>\n<td align=\"right\">236.450.364<\/td>\n<\/tr>\n<tr>\n<td>letzte Mitteilung<\/td>\n<td align=\"right\">4,90 %<\/td>\n<td align=\"right\">2,19 %<\/td>\n<td align=\"right\">7,09 %<\/td>\n<td align=\"right\">\/<\/td>\n<\/tr>\n<\/table>\n<p><strong>7. Einzelheiten zu den Stimmrechtsbest\u00e4nden<\/strong><br \/>\n<br \/><strong>a. Stimmrechte (\u00a7\u00a7 33, 34 WpHG)<\/strong><\/p>\n<table border=\"1\">\n<tr>\n<td>ISIN<\/td>\n<td colspan=\"2\" align=\"center\">absolut<\/td>\n<td colspan=\"2\" align=\"center\">in %<\/td>\n<\/tr>\n<tr>\n<td>\u00a0<\/td>\n<td align=\"right\">direkt <br \/>(\u00a7 33 WpHG)<\/td>\n<td align=\"right\">zugerechnet <br \/>(\u00a7 34 WpHG)<\/td>\n<td align=\"right\">direkt <br \/>(\u00a7 33 WpHG)<\/td>\n<td align=\"right\">zugerechnet <br \/>(\u00a7 34 WpHG)<\/td>\n<\/tr>\n<tr>\n<td>DE000A0D6554<\/td>\n<td align=\"right\">0<\/td>\n<td align=\"right\">12.282.919<\/td>\n<td align=\"right\">0,00 %<\/td>\n<td align=\"right\">5,19 %<\/td>\n<\/tr>\n<tr>\n<td><strong>Summe<\/strong><\/td>\n<td colspan=\"2\" align=\"center\">12.282.919<\/td>\n<td colspan=\"2\" align=\"center\">5,19 %<\/td>\n<\/tr>\n<\/table>\n<p><strong>b.1. Instrumente i.S.d. \u00a7 38 Abs. 1 Nr. 1 WpHG<\/strong><\/p>\n<table border=\"1\">\n<tr>\n<td>Art des Instruments<\/td>\n<td>F\u00e4lligkeit \/ Verfall<\/td>\n<td>Aus\u00fcbungszeitraum \/ Laufzeit<\/td>\n<td align=\"right\">Stimmrechte absolut<\/td>\n<td align=\"right\">Stimmrechte in %<\/td>\n<\/tr>\n<tr>\n<td>Right to recall lent shares<\/td>\n<td \/>\n<td>Jederzeit<\/td>\n<td align=\"right\">1.882.985<\/td>\n<td align=\"right\">0,80 %<\/td>\n<\/tr>\n<tr>\n<td>Right of use over shares<\/td>\n<td \/>\n<td>Jederzeit<\/td>\n<td align=\"right\">253.751<\/td>\n<td align=\"right\">0,11 %<\/td>\n<\/tr>\n<tr>\n<td>Call option<\/td>\n<td>45646<\/td>\n<td \/>\n<td align=\"right\">210.000<\/td>\n<td align=\"right\">0,09 %<\/td>\n<\/tr>\n<tr>\n<td>\u00a0<\/td>\n<td>\u00a0<\/td>\n<td><strong>Summe<\/strong><\/td>\n<td align=\"right\">2.346.736<\/td>\n<td align=\"right\">0,99 %<\/td>\n<\/tr>\n<\/table>\n<p><strong>b.2. Instrumente i.S.d. \u00a7 38 Abs. 1 Nr. 2 WpHG<\/strong><\/p>\n<table border=\"1\">\n<tr>\n<td>Art des Instruments<\/td>\n<td>F\u00e4lligkeit \/ Verfall<\/td>\n<td>Aus\u00fcbungszeitraum \/ Laufzeit<\/td>\n<td>Barausgleich oder physische Abwicklung<\/td>\n<td align=\"right\">Stimmrechte absolut<\/td>\n<td align=\"right\">Stimmrechte in %<\/td>\n<\/tr>\n<tr>\n<td>Convertible Bonds<\/td>\n<td>14\/04\/2030<\/td>\n<td>14\/04\/2023 -30\/03\/2030<\/td>\n<td>Physisch<\/td>\n<td align=\"right\">1.970.756<\/td>\n<td align=\"right\">0,83 %<\/td>\n<\/tr>\n<tr>\n<td>Right to recall convertible bonds (DE000A351MA2)<\/td>\n<td>&#8211;<\/td>\n<td>Jederzeit<\/td>\n<td>Physisch<\/td>\n<td align=\"right\">139.860<\/td>\n<td align=\"right\">0,06 %<\/td>\n<\/tr>\n<tr>\n<td>Swaps on Baskets<\/td>\n<td>28\/11\/2024<\/td>\n<td \/>\n<td>Bar<\/td>\n<td align=\"right\">148.000<\/td>\n<td align=\"right\">0,06 %<\/td>\n<\/tr>\n<tr>\n<td>Put option<\/td>\n<td>45646<\/td>\n<td \/>\n<td>Physisch<\/td>\n<td align=\"right\">533.000<\/td>\n<td align=\"right\">0,23 %<\/td>\n<\/tr>\n<tr>\n<td>\u00a0<\/td>\n<td>\u00a0<\/td>\n<td>\u00a0<\/td>\n<td><strong>Summe<\/strong><\/td>\n<td align=\"right\">2.791.616<\/td>\n<td align=\"right\">1,18 %<\/td>\n<\/tr>\n<\/table>\n<p><strong>8. Informationen in Bezug auf den Mitteilungspflichtigen<\/strong><\/p>\n<table border=\"1\">\n<tr>\n<td>\u00a0<\/td>\n<td>Mitteilungspflichtiger (3.) wird weder beherrscht noch beherrscht Mitteilungspflichtiger andere Unternehmen, die Stimmrechte des Emittenten (1.) halten oder denen Stimmrechte des Emittenten zugerechnet werden.<\/td>\n<\/tr>\n<tr>\n<td>X<\/td>\n<td>Vollst\u00e4ndige Kette der Tochterunternehmen, beginnend mit der obersten beherrschenden Person oder dem obersten beherrschenden Unternehmen:<\/td>\n<\/tr>\n<\/table>\n<p><\/p>\n<table border=\"1\">\n<tr>\n<td>Unternehmen<\/td>\n<td align=\"right\">Stimmrechte in %, wenn 3% oder h\u00f6her<\/td>\n<td align=\"right\">Instrumente in %, wenn 5% oder h\u00f6her<\/td>\n<td align=\"right\">Summe in %, wenn 5% oder h\u00f6her<\/td>\n<\/tr>\n<tr>\n<td>UBS Group AG<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<\/tr>\n<tr>\n<td>UBS AG<\/td>\n<td align=\"right\">5,00 %<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\">5,67 %<\/td>\n<\/tr>\n<tr>\n<td>UBS Switzerland AG<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<\/tr>\n<tr>\n<td>&#8211;<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<\/tr>\n<tr>\n<td>UBS Group AG<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<\/tr>\n<tr>\n<td>UBS AG<\/td>\n<td align=\"right\">5,00 %<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\">5,67 %<\/td>\n<\/tr>\n<tr>\n<td>UBS Asset Management AG<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<\/tr>\n<tr>\n<td>UBS Asset Management Holding (No. 2) Ltd<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<\/tr>\n<tr>\n<td>UBS Asset Management Holding Ltd<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<\/tr>\n<tr>\n<td>UBS Asset Management (UK) Limited<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<\/tr>\n<tr>\n<td>&#8211;<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<\/tr>\n<tr>\n<td>UBS Group AG<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<\/tr>\n<tr>\n<td>UBS AG<\/td>\n<td align=\"right\">5,00 %<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\">5,67 %<\/td>\n<\/tr>\n<tr>\n<td>UBS Asset Management AG<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<\/tr>\n<tr>\n<td>UBS Fund Management (Luxembourg) SA<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<\/tr>\n<tr>\n<td>&#8211;<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<\/tr>\n<tr>\n<td>UBS Group AG<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<\/tr>\n<tr>\n<td>UBS AG<\/td>\n<td align=\"right\">5,00 %<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\">5,67 %<\/td>\n<\/tr>\n<tr>\n<td>UBS Asset Management AG<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<\/tr>\n<tr>\n<td>UBS Asset Management Switzerland AG<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<\/tr>\n<tr>\n<td>UBS Fund Management (Switzerland) AG<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<\/tr>\n<tr>\n<td>&#8211;<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<\/tr>\n<tr>\n<td>UBS Group AG<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<\/tr>\n<tr>\n<td>UBS AG<\/td>\n<td align=\"right\">5,00 %<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\">5,67 %<\/td>\n<\/tr>\n<tr>\n<td>UBS Americas Holding LLC<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<\/tr>\n<tr>\n<td>UBS Americas Inc.<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<\/tr>\n<tr>\n<td>UBS Securities LLC<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<\/tr>\n<tr>\n<td>&#8211;<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<\/tr>\n<tr>\n<td>UBS Group AG<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<\/tr>\n<tr>\n<td>Credit Suisse AG<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<\/tr>\n<tr>\n<td>Credit Suisse International<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<\/tr>\n<tr>\n<td>&#8211;<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<\/tr>\n<tr>\n<td>UBS Group AG<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<\/tr>\n<tr>\n<td>Credit Suisse AG<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<\/tr>\n<tr>\n<td>Credit Suisse (Schweiz) AG<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<\/tr>\n<tr>\n<td>&#8211;<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<\/tr>\n<tr>\n<td>UBS Group AG<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<\/tr>\n<tr>\n<td>Credit Suisse AG<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<\/tr>\n<tr>\n<td>Credit Suisse Asset Management International Holding Ltd<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<\/tr>\n<tr>\n<td>Credit Suisse Asset Management &amp;<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<\/tr>\n<tr>\n<td>Investor Services (Schweiz) Holding AG<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<\/tr>\n<tr>\n<td>Credit Suisse Funds AG<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<\/tr>\n<\/table>\n<p><strong>9. Bei Vollmacht gem\u00e4\u00df \u00a7 34 Abs. 3 WpHG<\/strong><br \/>\n(nur m\u00f6glich bei einer Zurechnung nach \u00a7 34 Abs. 1 Satz 1 Nr. 6 WpHG)<\/p>\n<p>Datum der Hauptversammlung: <br \/>\nGesamtstimmrechtsanteile (6.) nach der Hauptversammlung:<\/p>\n<table border=\"1\">\n<tr>\n<td align=\"right\">Anteil Stimmrechte<\/td>\n<td align=\"right\">Anteil Instrumente<\/td>\n<td align=\"right\">Summe Anteile<\/td>\n<\/tr>\n<tr>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<td align=\"right\"> %<\/td>\n<\/tr>\n<\/table>\n<p><strong>10. Sonstige Informationen:<\/strong><\/p>\n<table border=\"1\">\n<tr>\n<td>\u00a0<\/td>\n<\/tr>\n<\/table>\n<p>\nDatum<\/p>\n<table border=\"1\">\n<tr>\n<td>26.10.2023<\/td>\n<\/tr>\n<\/table>\n<p><\/div>\n<p><\/p>\n<hr \/>\n<p>\n27.10.2023 CET\/CEST Die EQS Distributionsservices umfassen gesetzliche Meldepflichten, Corporate News\/Finanznachrichten und Pressemitteilungen.<br \/>Medienarchiv unter https:\/\/eqs-news.com<\/p>\n<hr \/>\n<\/td>\n<\/tr>\n<\/table>\n<table>\n<tr>\n<td align=\"left\" valign=\"top\">Sprache:<\/td>\n<td align=\"left\" valign=\"top\">Deutsch<\/td>\n<\/tr>\n<tr>\n<td align=\"left\" valign=\"top\">Unternehmen:<\/td>\n<td align=\"left\" valign=\"top\">Nordex SE<\/td>\n<\/tr>\n<tr>\n<td align=\"left\" valign=\"top\" \/>\n<td align=\"left\" valign=\"top\">Erich-Schlesinger-Stra\u00dfe 50<\/td>\n<\/tr>\n<tr>\n<td align=\"left\" valign=\"top\" \/>\n<td align=\"left\" valign=\"top\">18059 Rostock<\/td>\n<\/tr>\n<tr>\n<td align=\"left\" valign=\"top\" \/>\n<td align=\"left\" valign=\"top\">Deutschland<\/td>\n<\/tr>\n<tr>\n<td align=\"left\" valign=\"top\">Internet:<\/td>\n<td align=\"left\" valign=\"top\">www.nordex-online.com<\/td>\n<\/tr>\n<\/table>\n<p><\/p>\n<table border=\"0\">\n<tr>\n<td align=\"left\" valign=\"top\" colspan=\"2\" \/>\n<\/tr>\n<\/table>\n<table border=\"0\">\n<tr>\n<td align=\"left\" valign=\"top\" colspan=\"2\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td align=\"left\" valign=\"top\">Ende der Mitteilung<\/td>\n<td align=\"left\" valign=\"top\">EQS News-Service<\/td>\n<\/tr>\n<\/table>\n<table border=\"0\">\n<tr>\n<td>\n<hr \/>\n<\/td>\n<\/tr>\n<\/table>\n<p>1759499\u00a0\u00a027.10.2023\u00a0CET\/CEST\n<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/eqs-cockpit.com\/cgi-bin\/fncls.ssp?fn=show_t_gif&amp;application_id=1759499&amp;application_name=news&amp;site_id=airport_aws\" alt=\"fncls.ssp?fn=show_t_gif&amp;application_id=1759499&amp;application_name=news&amp;site_id=airport_aws\" width=\"0\" height=\"0\" border=\"0\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nordex SE Nordex SE: Ver\u00f6ffentlichung gem\u00e4\u00df \u00a7 40 Abs. 1 WpHG mit dem Ziel der europaweiten Verbreitung 27.10.2023 \/ 11:14 CET\/CEST Ver\u00f6ffentlichung einer Stimmrechtsmitteilung \u00fcbermittelt durch EQS News &#8211; ein Service der EQS Group AG. F\u00fcr den Inhalt der Mitteilung ist der Emittent \/ Herausgeber verantwortlich. Stimmrechtsmitteilung 1. Angaben zum Emittenten Name: Nordex SE Stra\u00dfe, [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_trash_the_other_posts":false,"editor_notices":[],"footnotes":""},"categories":[1250,1254],"tags":[],"class_list":["post-40606","post","type-post","status-publish","format-standard","hentry","category-investor-relations","category-pvr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>UBS Group AG, Z\u00fcrich, Schweiz - Nordex SE - Deutsch<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.nordex-online.com\/de\/2023\/10\/nordex-se-veroeffentlichung-gemaess-\u00a7-40-abs-1-wphg-mit-dem-ziel-der-europaweiten-verbreitung-223\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"UBS Group AG, Z\u00fcrich, Schweiz\" \/>\n<meta property=\"og:description\" content=\"Nordex SE Nordex SE: Ver\u00f6ffentlichung gem\u00e4\u00df \u00a7 40 Abs. 1 WpHG mit dem Ziel der europaweiten Verbreitung 27.10.2023 \/ 11:14 CET\/CEST Ver\u00f6ffentlichung einer Stimmrechtsmitteilung \u00fcbermittelt durch EQS News &#8211; ein Service der EQS Group AG. F\u00fcr den Inhalt der Mitteilung ist der Emittent \/ Herausgeber verantwortlich. Stimmrechtsmitteilung 1. Angaben zum Emittenten Name: Nordex SE Stra\u00dfe, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nordex-online.com\/de\/2023\/10\/nordex-se-veroeffentlichung-gemaess-\u00a7-40-abs-1-wphg-mit-dem-ziel-der-europaweiten-verbreitung-223\/\" \/>\n<meta property=\"og:site_name\" content=\"Nordex SE - Deutsch\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-27T09:14:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-14T06:43:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eqs-cockpit.com\/cgi-bin\/fncls.ssp?fn=show_t_gif&amp;application_id=1759499&amp;application_name=news&amp;site_id=airport_aws\" \/>\n<meta name=\"author\" content=\"aeckert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"aeckert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2023\\\/10\\\/nordex-se-veroeffentlichung-gemaess-%c2%a7-40-abs-1-wphg-mit-dem-ziel-der-europaweiten-verbreitung-223\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2023\\\/10\\\/nordex-se-veroeffentlichung-gemaess-%c2%a7-40-abs-1-wphg-mit-dem-ziel-der-europaweiten-verbreitung-223\\\/\"},\"author\":{\"name\":\"aeckert\",\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/#\\\/schema\\\/person\\\/81621b8f0d2d2d605ac828cef137de95\"},\"headline\":\"UBS Group AG, Z\u00fcrich, Schweiz\",\"datePublished\":\"2023-10-27T09:14:33+00:00\",\"dateModified\":\"2025-08-14T06:43:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2023\\\/10\\\/nordex-se-veroeffentlichung-gemaess-%c2%a7-40-abs-1-wphg-mit-dem-ziel-der-europaweiten-verbreitung-223\\\/\"},\"wordCount\":524,\"publisher\":{\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2023\\\/10\\\/nordex-se-veroeffentlichung-gemaess-%c2%a7-40-abs-1-wphg-mit-dem-ziel-der-europaweiten-verbreitung-223\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eqs-cockpit.com\\\/cgi-bin\\\/fncls.ssp?fn=show_t_gif&amp;application_id=1759499&amp;application_name=news&amp;site_id=airport_aws\",\"articleSection\":[\"Investorenbeziehungen\",\"Stimmrechte\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2023\\\/10\\\/nordex-se-veroeffentlichung-gemaess-%c2%a7-40-abs-1-wphg-mit-dem-ziel-der-europaweiten-verbreitung-223\\\/\",\"url\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2023\\\/10\\\/nordex-se-veroeffentlichung-gemaess-%c2%a7-40-abs-1-wphg-mit-dem-ziel-der-europaweiten-verbreitung-223\\\/\",\"name\":\"UBS Group AG, Z\u00fcrich, Schweiz - Nordex SE - Deutsch\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2023\\\/10\\\/nordex-se-veroeffentlichung-gemaess-%c2%a7-40-abs-1-wphg-mit-dem-ziel-der-europaweiten-verbreitung-223\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2023\\\/10\\\/nordex-se-veroeffentlichung-gemaess-%c2%a7-40-abs-1-wphg-mit-dem-ziel-der-europaweiten-verbreitung-223\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eqs-cockpit.com\\\/cgi-bin\\\/fncls.ssp?fn=show_t_gif&amp;application_id=1759499&amp;application_name=news&amp;site_id=airport_aws\",\"datePublished\":\"2023-10-27T09:14:33+00:00\",\"dateModified\":\"2025-08-14T06:43:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2023\\\/10\\\/nordex-se-veroeffentlichung-gemaess-%c2%a7-40-abs-1-wphg-mit-dem-ziel-der-europaweiten-verbreitung-223\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2023\\\/10\\\/nordex-se-veroeffentlichung-gemaess-%c2%a7-40-abs-1-wphg-mit-dem-ziel-der-europaweiten-verbreitung-223\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2023\\\/10\\\/nordex-se-veroeffentlichung-gemaess-%c2%a7-40-abs-1-wphg-mit-dem-ziel-der-europaweiten-verbreitung-223\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eqs-cockpit.com\\\/cgi-bin\\\/fncls.ssp?fn=show_t_gif&amp;application_id=1759499&amp;application_name=news&amp;site_id=airport_aws\",\"contentUrl\":\"https:\\\/\\\/eqs-cockpit.com\\\/cgi-bin\\\/fncls.ssp?fn=show_t_gif&amp;application_id=1759499&amp;application_name=news&amp;site_id=airport_aws\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/2023\\\/10\\\/nordex-se-veroeffentlichung-gemaess-%c2%a7-40-abs-1-wphg-mit-dem-ziel-der-europaweiten-verbreitung-223\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"UBS Group AG, Z\u00fcrich, Schweiz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/\",\"name\":\"Nordex SE - Deutsch\",\"description\":\"Manufacture, installation and maintenance of wind turbines.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/#organization\",\"name\":\"Nordex SE - Deutsch\",\"url\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.nordex-online.com\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/07\\\/cropped-cropped-Combined-Logos_cmyk_PNG.png\",\"contentUrl\":\"https:\\\/\\\/www.nordex-online.com\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/07\\\/cropped-cropped-Combined-Logos_cmyk_PNG.png\",\"width\":1181,\"height\":353,\"caption\":\"Nordex SE - Deutsch\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/#\\\/schema\\\/person\\\/81621b8f0d2d2d605ac828cef137de95\",\"name\":\"aeckert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9bb1da8fdca865f8714afd486408f3f4d26ef53f3ff2e44201e2a0a3b5e3c6b2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9bb1da8fdca865f8714afd486408f3f4d26ef53f3ff2e44201e2a0a3b5e3c6b2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9bb1da8fdca865f8714afd486408f3f4d26ef53f3ff2e44201e2a0a3b5e3c6b2?s=96&d=mm&r=g\",\"caption\":\"aeckert\"},\"url\":\"https:\\\/\\\/www.nordex-online.com\\\/de\\\/author\\\/antje\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"UBS Group AG, Z\u00fcrich, Schweiz - Nordex SE - Deutsch","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.nordex-online.com\/de\/2023\/10\/nordex-se-veroeffentlichung-gemaess-\u00a7-40-abs-1-wphg-mit-dem-ziel-der-europaweiten-verbreitung-223\/","og_locale":"de_DE","og_type":"article","og_title":"UBS Group AG, Z\u00fcrich, Schweiz","og_description":"Nordex SE Nordex SE: Ver\u00f6ffentlichung gem\u00e4\u00df \u00a7 40 Abs. 1 WpHG mit dem Ziel der europaweiten Verbreitung 27.10.2023 \/ 11:14 CET\/CEST Ver\u00f6ffentlichung einer Stimmrechtsmitteilung \u00fcbermittelt durch EQS News &#8211; ein Service der EQS Group AG. F\u00fcr den Inhalt der Mitteilung ist der Emittent \/ Herausgeber verantwortlich. Stimmrechtsmitteilung 1. Angaben zum Emittenten Name: Nordex SE Stra\u00dfe, [&hellip;]","og_url":"https:\/\/www.nordex-online.com\/de\/2023\/10\/nordex-se-veroeffentlichung-gemaess-\u00a7-40-abs-1-wphg-mit-dem-ziel-der-europaweiten-verbreitung-223\/","og_site_name":"Nordex SE - Deutsch","article_published_time":"2023-10-27T09:14:33+00:00","article_modified_time":"2025-08-14T06:43:55+00:00","og_image":[{"url":"https:\/\/eqs-cockpit.com\/cgi-bin\/fncls.ssp?fn=show_t_gif&amp;application_id=1759499&amp;application_name=news&amp;site_id=airport_aws","type":"","width":"","height":""}],"author":"aeckert","twitter_card":"summary_large_image","twitter_misc":{"Geschrieben von":"aeckert","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.nordex-online.com\/de\/2023\/10\/nordex-se-veroeffentlichung-gemaess-%c2%a7-40-abs-1-wphg-mit-dem-ziel-der-europaweiten-verbreitung-223\/#article","isPartOf":{"@id":"https:\/\/www.nordex-online.com\/de\/2023\/10\/nordex-se-veroeffentlichung-gemaess-%c2%a7-40-abs-1-wphg-mit-dem-ziel-der-europaweiten-verbreitung-223\/"},"author":{"name":"aeckert","@id":"https:\/\/www.nordex-online.com\/de\/#\/schema\/person\/81621b8f0d2d2d605ac828cef137de95"},"headline":"UBS Group AG, Z\u00fcrich, Schweiz","datePublished":"2023-10-27T09:14:33+00:00","dateModified":"2025-08-14T06:43:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.nordex-online.com\/de\/2023\/10\/nordex-se-veroeffentlichung-gemaess-%c2%a7-40-abs-1-wphg-mit-dem-ziel-der-europaweiten-verbreitung-223\/"},"wordCount":524,"publisher":{"@id":"https:\/\/www.nordex-online.com\/de\/#organization"},"image":{"@id":"https:\/\/www.nordex-online.com\/de\/2023\/10\/nordex-se-veroeffentlichung-gemaess-%c2%a7-40-abs-1-wphg-mit-dem-ziel-der-europaweiten-verbreitung-223\/#primaryimage"},"thumbnailUrl":"https:\/\/eqs-cockpit.com\/cgi-bin\/fncls.ssp?fn=show_t_gif&amp;application_id=1759499&amp;application_name=news&amp;site_id=airport_aws","articleSection":["Investorenbeziehungen","Stimmrechte"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.nordex-online.com\/de\/2023\/10\/nordex-se-veroeffentlichung-gemaess-%c2%a7-40-abs-1-wphg-mit-dem-ziel-der-europaweiten-verbreitung-223\/","url":"https:\/\/www.nordex-online.com\/de\/2023\/10\/nordex-se-veroeffentlichung-gemaess-%c2%a7-40-abs-1-wphg-mit-dem-ziel-der-europaweiten-verbreitung-223\/","name":"UBS Group AG, Z\u00fcrich, Schweiz - Nordex SE - Deutsch","isPartOf":{"@id":"https:\/\/www.nordex-online.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.nordex-online.com\/de\/2023\/10\/nordex-se-veroeffentlichung-gemaess-%c2%a7-40-abs-1-wphg-mit-dem-ziel-der-europaweiten-verbreitung-223\/#primaryimage"},"image":{"@id":"https:\/\/www.nordex-online.com\/de\/2023\/10\/nordex-se-veroeffentlichung-gemaess-%c2%a7-40-abs-1-wphg-mit-dem-ziel-der-europaweiten-verbreitung-223\/#primaryimage"},"thumbnailUrl":"https:\/\/eqs-cockpit.com\/cgi-bin\/fncls.ssp?fn=show_t_gif&amp;application_id=1759499&amp;application_name=news&amp;site_id=airport_aws","datePublished":"2023-10-27T09:14:33+00:00","dateModified":"2025-08-14T06:43:55+00:00","breadcrumb":{"@id":"https:\/\/www.nordex-online.com\/de\/2023\/10\/nordex-se-veroeffentlichung-gemaess-%c2%a7-40-abs-1-wphg-mit-dem-ziel-der-europaweiten-verbreitung-223\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.nordex-online.com\/de\/2023\/10\/nordex-se-veroeffentlichung-gemaess-%c2%a7-40-abs-1-wphg-mit-dem-ziel-der-europaweiten-verbreitung-223\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.nordex-online.com\/de\/2023\/10\/nordex-se-veroeffentlichung-gemaess-%c2%a7-40-abs-1-wphg-mit-dem-ziel-der-europaweiten-verbreitung-223\/#primaryimage","url":"https:\/\/eqs-cockpit.com\/cgi-bin\/fncls.ssp?fn=show_t_gif&amp;application_id=1759499&amp;application_name=news&amp;site_id=airport_aws","contentUrl":"https:\/\/eqs-cockpit.com\/cgi-bin\/fncls.ssp?fn=show_t_gif&amp;application_id=1759499&amp;application_name=news&amp;site_id=airport_aws"},{"@type":"BreadcrumbList","@id":"https:\/\/www.nordex-online.com\/de\/2023\/10\/nordex-se-veroeffentlichung-gemaess-%c2%a7-40-abs-1-wphg-mit-dem-ziel-der-europaweiten-verbreitung-223\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.nordex-online.com\/de\/"},{"@type":"ListItem","position":2,"name":"UBS Group AG, Z\u00fcrich, Schweiz"}]},{"@type":"WebSite","@id":"https:\/\/www.nordex-online.com\/de\/#website","url":"https:\/\/www.nordex-online.com\/de\/","name":"Nordex SE - Deutsch","description":"Manufacture, installation and maintenance of wind turbines.","publisher":{"@id":"https:\/\/www.nordex-online.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nordex-online.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.nordex-online.com\/de\/#organization","name":"Nordex SE - Deutsch","url":"https:\/\/www.nordex-online.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.nordex-online.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.nordex-online.com\/wp-content\/uploads\/sites\/3\/2024\/07\/cropped-cropped-Combined-Logos_cmyk_PNG.png","contentUrl":"https:\/\/www.nordex-online.com\/wp-content\/uploads\/sites\/3\/2024\/07\/cropped-cropped-Combined-Logos_cmyk_PNG.png","width":1181,"height":353,"caption":"Nordex SE - Deutsch"},"image":{"@id":"https:\/\/www.nordex-online.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.nordex-online.com\/de\/#\/schema\/person\/81621b8f0d2d2d605ac828cef137de95","name":"aeckert","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/9bb1da8fdca865f8714afd486408f3f4d26ef53f3ff2e44201e2a0a3b5e3c6b2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9bb1da8fdca865f8714afd486408f3f4d26ef53f3ff2e44201e2a0a3b5e3c6b2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9bb1da8fdca865f8714afd486408f3f4d26ef53f3ff2e44201e2a0a3b5e3c6b2?s=96&d=mm&r=g","caption":"aeckert"},"url":"https:\/\/www.nordex-online.com\/de\/author\/antje\/"}]}},"_links":{"self":[{"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/posts\/40606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/comments?post=40606"}],"version-history":[{"count":1,"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/posts\/40606\/revisions"}],"predecessor-version":[{"id":45914,"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/posts\/40606\/revisions\/45914"}],"wp:attachment":[{"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/media?parent=40606"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/categories?post=40606"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nordex-online.com\/de\/wp-json\/wp\/v2\/tags?post=40606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}